{"id":33002,"date":"2021-02-24T08:00:43","date_gmt":"2021-02-24T07:00:43","guid":{"rendered":"http:\/\/stefan-taege.de\/kasia\/?p=33002"},"modified":"2021-02-24T12:15:12","modified_gmt":"2021-02-24T11:15:12","slug":"reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen","status":"publish","type":"post","link":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/","title":{"rendered":"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen"},"content":{"rendered":"<p><em>Einkaufen!<\/em><\/p>\n<p><em>H\u00e4??<\/em><\/p>\n<p>Fernweh. Wer von uns gerne reist, hat zur Zeit die A*- Karte gezogen. Von fernen Orten kann man nur noch tr\u00e4umen und jaulend durchs Wohnzimmer tigern, ein Reisebuch in der einen und die Fotosammlung in der anderen Hand.<\/p>\n<p>Wenn es mich so richtig schlimm erwischt; so, dass ich den Mond anheulen k\u00f6nnte und meine Augen nur noch zwei Bildschirme sind, auf denen pausenlos BBC World l\u00e4uft, dann mache ich folgendes:<!--more--><\/p>\n<p>Anstatt mir irgendwelche Orte ganz in meiner N\u00e4he anzugucken, die angeblich aussehen sollen wie&#8230; (hier beliebige weltber\u00fchmte Destination einf\u00fcgen), packe ich mir mein Backpack. Ich schnappe mir den Geldbeutel und ein paar Einkaufsnetze, ziehe meine Wanderschuhe an und mache mich authentisch zu Fu\u00df auf zum n\u00e4chsten t\u00fcrkischen Supermarkt. Am besten an einem Samstag, wenn es so richtig voll und lebhaft ist und die Leutchen mit ihren Familien zum Gro\u00dfeinkauf fahren. Dann geht es sch\u00f6n gesch\u00e4ftig zu, fast wie auf einem orientalischem Bazar. Gut, mit viel Fantasie. Die n\u00f6tige Fantasie habe ich, was ist mir sonst geblieben.<\/p>\n<p>Dort angekommen verlasse ich die olle, deutsche Wirklichkeit und lasse mich in eine andere Welt hinein fallen. Mit einem Riesen-Plumps. Da sind sie wieder, meine ungewohnten Eindr\u00fccke, fremde Sprachen, exotische Ger\u00fcche nach gebratenem Fisch (das ist der Fischstand vor dem Supermarkt&#8230;), Gew\u00fcrzen und Pfefferminze.<\/p>\n<p>Stapelweise lockt das bunte Obst, jedes zweite Produkt im Regal l\u00e4sst in meinen Augen Fragezeichen aufleuchten. Schau, was ist denn das? Hm, das Hummus nehme ich aber noch mit. Ein Bund Pfefferminze wandert in meinen Einkaufskorb. Ich wei\u00df noch nicht, was ich damit machen werde &#8211; ich wei\u00df, man kocht damit Tee, aber in meiner Ausf\u00fchrung w\u00fcrde der Tee wohl nix werden&#8230; Doch der minzige Geruch steigt in meine Nase und ich kann nicht widerstehen. Alleine die Tatsache, dass ich die ganzen Sachen rund zwei Kilometer weit nach Hause tragen m\u00fcsste, h\u00e4lt mich davon ab, den Laden leer zu r\u00e4umen. Meine Synapsen feuern wieder auf Hochtouren.<\/p>\n<p>&#8222;Ich zahle mit Karte.&#8220; An der Kasse wird es wieder ein bisschen deutsch. Die EC wandert in den Schlitz, die Eink\u00e4ufe in meinen Backpack. Von irgendwoher steigt mir noch immer penetrant die Pfefferminze in die Nase.<\/p>\n<p>Sp\u00e4ter laufe ich dann, vollbepackt wie ein Packkamel, die ollen, deutschen Stra\u00dfen wieder zur\u00fcck nach Hause. Der Backpack wiegt schwer auf meinem R\u00fccken, und doch beschert mir dieses vertraute Gewicht ein Gl\u00fccksgef\u00fchl. Fast so, als w\u00fcrde ich wieder durch irgend einen fernen Ort laufen, all mein Gep\u00e4ck auf dem R\u00fccken, auf der Suche nach meinem Hostel. Schwei\u00dfperlen auf der Stirn. Ein Grinsen im Gesicht.<\/p>\n<p>Dieser Fernweh-Tipp funktioniert ganz gut mit jedem anderen Supermarkt, der von dem abweicht, wo ihr sonst immer einkaufen geht. Es kann genauso gut ein Asiashop sein oder ein polnisch-russischer Spezialit\u00e4tenladen. Oder ein italienischer Supermarkt. Wer das Gl\u00fcck hat, in einer gro\u00dfen Stadt zu wohnen, hat da die volle Auswahl. Hier findet ihr Produkte, die sonst wohl nicht in eurem Einkaufskorb gelandet w\u00e4ren. Ihr k\u00f6nnt euch inspirieren lassen und etwas leckeres daraus kochen. In den kleinen Lebensmittelgesch\u00e4ften werdet ihr, wenn ihr Gl\u00fcck habt, zudem noch richtig gut beraten. In einem kleinen, t\u00fcrkischen Shop in der Pfalz habe ich zu der mir unbekannten Pilzsorte (Butterpilze waren das, glaube ich) eine Anleitung an die Hand bekommen, wie ich selbige am besten zubereite. Dazu gab es ein Vorschlag f\u00fcr ein Pilzgericht-Rezept und der freundliche Herr hat mir alle n\u00f6tigen Zutaten gleich zusammengesucht.<\/p>\n<p>Nicht alle Aspekte des oben Beschriebenen sind mit voller Ernsthaftigkeit zu nehmen. Nat\u00fcrlich empfehle ich es zur Zeit keinem, ausgerechnet zu den Sto\u00dfzeiten, wenn der Laden brechend voll ist, einkaufen zu gehen. Ich denke, das ist klar. Ich muss es aber nochmal dazu schreiben, es gibt immer wieder welche, die witzige Anekdoten f\u00fcr bare M\u00fcnze nehmen \ud83d\ude09<\/p>\n<p>Das ist f\u00fcr mich, was ich unter einer Mikro-Reise verstehe. Viele interpretieren Mikro-Reisen als winzig kleine Ausfl\u00fcge, als Kurztrips quasi um die Ecke. Das kann man so sehen, ja. Ich habe Mikro-Reisen f\u00fcr mich anders definiert. Es sind f\u00fcr mich die kleinen Spr\u00fcnge in eine andere Kultur. Das herausgerissen werden aus der Normalit\u00e4t, das katapultiert werden in eine v\u00f6llig andere Umgebung, die stark an die Gef\u00fchle und Eindr\u00fccke im Urlaub erinnert. Und f\u00fcr die man nicht verreisen muss. Manchmal kommt so ein Mikro-Reisen-Flash komplett unerwartet. Manchmal ist es der <a href=\"https:\/\/stefan-taege.de\/kasia\/2018\/12\/02\/micro-reisen-ein-kleiner-sprung-in-eine-andere-welt\/\" target=\"_blank\" rel=\"noopener\">Kaffee, der auf Sand gebr\u00fcht wird<\/a> (was??). Oder der Raki-Abend bei einer Freundin. Mannheim ist eine so wunderbar multikulturelle Stadt. Und ein kurzes Eintauchen in diese &#8222;vierte Dimension&#8220; befl\u00fcgelt meine Reisesehnsucht mehr, stillt das Verlangen nach neuen Reizen wirksamer als alle Spazierg\u00e4nge und Wanderungen in der ach so sch\u00f6nen, vertrauten Umgebung zusammen.<\/p>\n<p>Meine Ausbeute des heutigen Einkaufstages: Bund Pfefferminze, Bund Dill, je ein P\u00e4ckchen rote und gr\u00fcne Linsen, schwarze Bohnen getrocknet, Kokosnussmilch, Joghurt, Granatapfel. Gut, f\u00fcr die meisten Sachen habe ich nicht wirklich einen Plan, was ich damit anstellen werde. Doch f\u00fcr die B\u00f6hnchen habe ich mich inspirieren lassen: hier ist ein Rezept f\u00fcr t\u00fcrkischen Bohneneintopf, <del>abgekupfert<\/del> inspiriert mit freundlichen Gr\u00fc\u00dfen von <a href=\"https:\/\/www.turkischegerichte.com\/turkischer-bohneneintopf-rezept-kuru-fasulye.html\" target=\"_blank\" rel=\"noopener\">TR Gerichte<\/a>, einer deutschsprachigen Website voll der leckersten t\u00fcrkischen Spezialit\u00e4ten zum Nachkochen.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"33236\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/20210221_222615\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?fit=1020%2C574&amp;ssl=1\" data-orig-size=\"1020,574\" data-comments-opened=\"1\" data-image-title=\"20210221_222615\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?fit=1020%2C574&amp;ssl=1\" class=\"alignnone size-full wp-image-33236\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?resize=1020%2C574&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"574\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?w=1020&amp;ssl=1 1020w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?resize=2048%2C1152&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222615-scaled.jpg?resize=107%2C60&amp;ssl=1 107w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h3>Rezept f\u00fcr T\u00fcrkischen Bohneneintopf<\/h3>\n<p>500g Bohnen \u00fcber Nacht im kalten Wasser einweichen lassen. 1 Zwiebel kleinhacken und mit je 1 EL Paprikamark und Tomatenmark in \u00d6l anbraten. Die Bohnen dazu geben, mit 600 ml Wasser \u00fcbergie\u00dfen. Kochen, bis die Bohnen durch sind. Nach Bedarf mit Salz und Pfeffer w\u00fcrzen.<\/p>\n<p><em>Hast du auch deine ganz speziellen Hacks, um der Reisesehnsucht zu entgehen? Und vor allem: wie lange h\u00e4lt ihre Wirkung an? Teile sie mit mir, wenn du m\u00f6chtest \ud83d\ude09<\/em><\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" data-services=\"facebook%7Cpinterest%7Ctumblr\" data-url=\"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/\" data-timestamp=\"1614168912\" data-backendurl=\"https:\/\/stefan-taege.de\/kasia\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2021%2F02%2F24%2Freisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen%2F&text=Reisesehnsucht%20und%20mein%20ungew%C3%B6hnlicher%20Weg%2C%20damit%20umzugehen\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2021%2F02%2F24%2Freisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span data-service=\"facebook\" style=\"color:#3b5998\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2021%2F02%2F24%2Freisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen%2F&media=https%3A%2F%2Fstefan-taege.de%2Fkasia%2Fwp-content%2Fuploads%2F2021%2F02%2F20210221_222549-scaled-e1613944209660.jpg&description=Reisesehnsucht%20und%20mein%20ungew%C3%B6hnlicher%20Weg%2C%20damit%20umzugehen\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span data-service=\"pinterest\" style=\"color:#cb2027\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button tumblr shariff-nocustomcolor\" style=\"background-color:#529ecc\"><a href=\"https:\/\/www.tumblr.com\/widgets\/share\/tool?posttype=link&canonicalUrl=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2021%2F02%2F24%2Freisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen%2F&tags=stefan-taege.de\" title=\"Bei tumblr teilen\" aria-label=\"Bei tumblr teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#36465d; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#36465d\" d=\"M18 14l0 7.3c0 1.9 0 2.9 0.2 3.5 0.2 0.5 0.7 1.1 1.2 1.4 0.7 0.4 1.5 0.6 2.4 0.6 1.6 0 2.6-0.2 4.2-1.3v4.8c-1.4 0.6-2.6 1-3.7 1.3-1.1 0.3-2.3 0.4-3.6 0.4-1.5 0-2.3-0.2-3.4-0.6-1.1-0.4-2.1-0.9-2.9-1.6-0.8-0.7-1.3-1.4-1.7-2.2s-0.5-1.9-0.5-3.4v-11.2h-4.3v-4.5c1.3-0.4 2.7-1 3.6-1.8 0.9-0.8 1.6-1.7 2.2-2.7 0.5-1.1 0.9-2.4 1.1-4.1h5.2l0 8h8v6h-8z\"\/><\/svg><\/span><span data-service=\"tumblr\" style=\"color:#36465d\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2021%2F02%2F24%2Freisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button rss shariff-nocustomcolor\" style=\"background-color:#ff8c00\"><a href=\"https:\/\/stefan-taege.de\/kasia\/feed\/rss\/\" title=\"RSS-feed\" aria-label=\"RSS-feed\" role=\"button\" class=\"shariff-link\" style=\"; background-color:#fe9312; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#fe9312\" d=\"M4.3 23.5c-2.3 0-4.3 1.9-4.3 4.3 0 2.3 1.9 4.2 4.3 4.2 2.4 0 4.3-1.9 4.3-4.2 0-2.3-1.9-4.3-4.3-4.3zM0 10.9v6.1c4 0 7.7 1.6 10.6 4.4 2.8 2.8 4.4 6.6 4.4 10.6h6.2c0-11.7-9.5-21.1-21.1-21.1zM0 0v6.1c14.2 0 25.8 11.6 25.8 25.9h6.2c0-17.6-14.4-32-32-32z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2021%2F02%2F24%2Freisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Einkaufen! H\u00e4?? Fernweh. Wer von uns gerne reist, hat zur Zeit die A*- Karte gezogen. Von fernen Orten kann man &hellip; <\/p>\n","protected":false},"author":1,"featured_media":33209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[2863,2864,2865],"class_list":["post-33002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized","tag-bohneneintopf","tag-reisefieber","tag-reisesehnsucht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen - windrose.rocks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kasia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/\"},\"author\":{\"name\":\"Kasia\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\"},\"headline\":\"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen\",\"datePublished\":\"2021-02-24T07:00:43+00:00\",\"dateModified\":\"2021-02-24T11:15:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/\"},\"wordCount\":987,\"commentCount\":19,\"image\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1\",\"keywords\":[\"Bohneneintopf\",\"Reisefieber\",\"Reisesehnsucht\"],\"articleSection\":[\"Z - Themen von A bis...\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/\",\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/\",\"name\":\"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen - windrose.rocks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1\",\"datePublished\":\"2021-02-24T07:00:43+00:00\",\"dateModified\":\"2021-02-24T11:15:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1\",\"width\":1020,\"height\":574},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2021\\\/02\\\/24\\\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#website\",\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\",\"name\":\"windrose.rocks\",\"description\":\"Erz\u00e4hlungen einer Reisenden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\",\"name\":\"Kasia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"caption\":\"Kasia\"},\"description\":\"Hi, ich bin Kasia, die Stimme von \\\"windrose.rocks\\\" :-) Treibt Dich die Frage um, was sich denn alles jenseits der heimischen Couch verbirgt, bist Du rastlos und neugierig wie ich und sp\u00fcrst den Drang in Dir, in die Welt hinaus zu gehen? Dann tue es! Ich nehme Dich mit auf meine Reisen und lasse Dich hautnah das Unterwegs sein miterleben - in all seinen Facetten. Lass Dich inspirieren, komm mit mir und warte nicht l\u00e4nger, denn... die Welt ist so gro\u00df und wir sind so klein, und es gibt noch so viel zu sehen! Die Welt wartet auf uns.\",\"sameAs\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\"],\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/author\\\/kasia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen - windrose.rocks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/","twitter_misc":{"Verfasst von":"Kasia","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#article","isPartOf":{"@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/"},"author":{"name":"Kasia","@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f"},"headline":"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen","datePublished":"2021-02-24T07:00:43+00:00","dateModified":"2021-02-24T11:15:12+00:00","mainEntityOfPage":{"@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/"},"wordCount":987,"commentCount":19,"image":{"@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1","keywords":["Bohneneintopf","Reisefieber","Reisesehnsucht"],"articleSection":["Z - Themen von A bis..."],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/","url":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/","name":"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen - windrose.rocks","isPartOf":{"@id":"https:\/\/stefan-taege.de\/kasia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#primaryimage"},"image":{"@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1","datePublished":"2021-02-24T07:00:43+00:00","dateModified":"2021-02-24T11:15:12+00:00","author":{"@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f"},"breadcrumb":{"@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#primaryimage","url":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1","contentUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1","width":1020,"height":574},{"@type":"BreadcrumbList","@id":"https:\/\/stefan-taege.de\/kasia\/2021\/02\/24\/reisesehnsucht-und-mein-ungewoehnlicher-weg-damit-umzugehen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stefan-taege.de\/kasia\/"},{"@type":"ListItem","position":2,"name":"Reisesehnsucht und mein ungew\u00f6hnlicher Weg, damit umzugehen"}]},{"@type":"WebSite","@id":"https:\/\/stefan-taege.de\/kasia\/#website","url":"https:\/\/stefan-taege.de\/kasia\/","name":"windrose.rocks","description":"Erz\u00e4hlungen einer Reisenden","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stefan-taege.de\/kasia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f","name":"Kasia","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","caption":"Kasia"},"description":"Hi, ich bin Kasia, die Stimme von \"windrose.rocks\" :-) Treibt Dich die Frage um, was sich denn alles jenseits der heimischen Couch verbirgt, bist Du rastlos und neugierig wie ich und sp\u00fcrst den Drang in Dir, in die Welt hinaus zu gehen? Dann tue es! Ich nehme Dich mit auf meine Reisen und lasse Dich hautnah das Unterwegs sein miterleben - in all seinen Facetten. Lass Dich inspirieren, komm mit mir und warte nicht l\u00e4nger, denn... die Welt ist so gro\u00df und wir sind so klein, und es gibt noch so viel zu sehen! Die Welt wartet auf uns.","sameAs":["https:\/\/stefan-taege.de\/kasia\/"],"url":"https:\/\/stefan-taege.de\/kasia\/author\/kasia\/"}]}},"jetpack_featured_media_url":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2021\/02\/20210221_222549-scaled-e1613944209660.jpg?fit=1020%2C574&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p7Ku1E-8Ai","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/33002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/comments?post=33002"}],"version-history":[{"count":10,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/33002\/revisions"}],"predecessor-version":[{"id":33237,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/33002\/revisions\/33237"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/media\/33209"}],"wp:attachment":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/media?parent=33002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/categories?post=33002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/tags?post=33002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}