{"id":2639,"date":"2016-11-10T05:00:27","date_gmt":"2016-11-10T04:00:27","guid":{"rendered":"http:\/\/stefan-taege.de\/kasia\/?p=2639"},"modified":"2023-06-29T20:21:16","modified_gmt":"2023-06-29T18:21:16","slug":"mexico-the-best-honeymoon-ever","status":"publish","type":"post","link":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/","title":{"rendered":"Mexico &#8211; the best honeymoon ever!"},"content":{"rendered":"<p><strong><span style=\"text-decoration: underline;\"><em>Gef\u00fchrt mit Vanessa am 12 August 2016<\/em><\/span><\/strong><\/p>\n<p><strong><em>Meine Apothekenfreundin Vanessa und Sebastiano, beide\u00a0erst k\u00fcrzlich\u00a0<a href=\"https:\/\/stefan-taege.de\/kasia\/category\/vanessas-hochzeitjuli-2016\/\" target=\"_blank\" rel=\"noopener noreferrer\">verm\u00e4hlt<\/a>, verbrachten ihre Hochzeitsreise in Playa del Carmen, Mexiko &#8211; zwei lange und doch viel zu kurze Wochen.<\/em><\/strong><!--more--><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9641\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/img-20160906-wa0002-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0002.jpg?fit=1600%2C496&amp;ssl=1\" data-orig-size=\"1600,496\" data-comments-opened=\"1\" data-image-title=\"IMG-20160906-WA0002\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0002.jpg?fit=1020%2C316&amp;ssl=1\" class=\"alignnone wp-image-9641 size-full\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0002.jpg?resize=1020%2C316&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"316\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0002.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0002.jpg?resize=300%2C93&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0002.jpg?resize=768%2C238&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0002.jpg?resize=1024%2C317&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p><em>Liebe Vanessa! Du hattest bereits im Vorfeld so einiges erz\u00e4hlt: Was Ihr erlebt habt oder Euch angeschaut habt&#8230; \u00a0Was w\u00fcrdest Du in Mexiko unbedingt jemandem weiterempfehlen, der noch nie dort war? Was sollte man auf jeden Fall erlebt haben \/ darf man nicht verpassen?<\/em><\/p>\n<p>Auf jeden Fall sich darauf einlassen, wie die Leute sind. Diese Lebenseinstellung zu \u00fcbernehmen f\u00fcr die Tage, die man dort ist, diese Leichtigkeit. Dann; <em>Chich\u00e9n<\/em>&#8211;<em>Itz\u00e1<\/em>, die Pyramide, eines von den sieben Weltwundern. Da finden diese Ballsport-Turniere statt, von denen ich schon mal erz\u00e4hlt hatte <em>(der Ball wird mit der H\u00fcfte ins Tor bef\u00f6rdert, Anm. der Red.)<\/em>. Es sind hunderte Leute dort, aber trotzdem nimmst du die vielen Leute um dich herum nicht wahr, du f\u00fchlst dich nicht, als wenn da so viele Leute sind&#8230; Du siehst nur die Pyramide, dich&#8230; und du willst unbedingt ein Foto von dir und der Pyramide haben&#8230;\u00a0<em>(sie lacht).<\/em><\/p>\n<p><em>Es ist wahrscheinlich wie mit dem schiefen Turm von Pisa, oder? Man will dann unbedingt sein albernes Touristenfoto davon&#8230;<\/em><\/p>\n<p>Ja, genau.<\/p>\n<p>Dort ist eine riesenlange Schlange &#8211; ein Weg &#8211; und ein H\u00e4ndler nach dem anderen. Es ist wie so ne Art Bazar und die verkaufen alle m\u00f6glichen Souvenirs und\u00a0du k\u00f6nntest bei jedem stehen bleiben und alles angucken, weil das so cool gemacht ist.<\/p>\n<p><em>Sind es vor allem selbstgemachte Sachen?<\/em><\/p>\n<p>Ja. Die schnitzen das auch manchmal gleich vor dir.<\/p>\n<p><em>Du hattest mir dieses Foto gezeigt, von dem Mann mit seinen geschnitzten Skulpturen; war das so etwas?<\/em><\/p>\n<p>Ja, aber das war in Villadollid, das ist eine spanisch angehauchte Stadt, gibts aber auch in Spanien.<\/p>\n<p><em>Was ich noch fragen wollte: Die H\u00e4ndler, waren die aufdringlich?\u00a0<\/em><\/p>\n<p>Nein, gar nicht&#8230; gaar nicht&#8230;<\/p>\n<p><em>&#8230;Ich kenn das noch von Italien mit ihren &#8222;kaufen, billiger, billiger!&#8220;<\/em><\/p>\n<p>Ja, das sagen die schon so, aber&#8230; also ich habe den direkten Vergleich mit\u00a0\u00c4gypten; dort packen sie dich manchmal einfach an der Hand und versuchen, dich in ihr Gesch\u00e4ft zu ziehen&#8230; Und in Mexico waren sie null aufdringlich, sie wollten kein Trinkgeld, gar nichts wollten sie haben. Voll gechillt, wirklich. Du hast dich wohl gef\u00fchlt, du h\u00e4ttest dort auch alleine als Frau im Rock rumspazieren\u00a0k\u00f6nnen und keiner h\u00e4tte dir etwas gesagt.<\/p>\n<p><em>Was waren die tollsten Dinge, die Ihr erlebt habt? So das Allersch\u00f6nste?<\/em><\/p>\n<p>Es war einfach die Erfahrung, dass ich mit Seba einmal wohin geflogen bin und wir komplett alleine waren. Es war nicht wie Berlin oder so, sondern es war einfach ein anderes Land, eine andere Kultur, Flitterwochen, Stress weg&#8230; Es war das Zusammensein, man hatte Angst; vielleicht wird es langweilig, aber es war doch nicht langweilig. Du hast \u00fcberall hin geschaut und warst beeindruckt, dachtest dir: Boah, was ist denn das? Das muss ich jetzt herausfinden&#8230; Sogar eine Kokosnuss hat mich beeindruckt, von daher&#8230; <em>(grinst)\u00a0<\/em>Ja&#8230; immer, wenn ich Kokosn\u00fcsse gesehen habe, musste ich sie fotografieren&#8230;<\/p>\n<p><em>Solange sie nicht von oben runterfallen&#8230;<\/em><\/p>\n<p>Das haben wir uns auch gedacht. Wei\u00dft du, wie viele Leute sterben an fallenden Kokosn\u00fcssen?<\/p>\n<p><em>Ich habs gelesen&#8230; so einige&#8230;<\/em><\/p>\n<p>Ja, schon heftig&#8230;<\/p>\n<p><em>Das Gesetz der Wahrscheinlichkeit&#8230;<\/em><\/p>\n<p><em>Es war Eure Hochzeitsreise; mitten aus den Hochzeitsvorbereitungen hinein ins Vergn\u00fcgen, und dann zwei Wochen lang am St\u00fcck zusammen im Urlaub &#8211; wie war es? War es ungewohnt f\u00fcr Euch? Gab es Spannungen?<\/em><\/p>\n<p>Voll sch\u00f6n <em>(kichert verliebt vor sich hin)<\/em> Voll sch\u00f6n war das&#8230; kein einziges Mal gestritten, kein einziges Mal. Wir haben uns eher geneckt, so nach dem Motto: Wer geht jetzt Wasser holen? Aber das war zum Spa\u00df. Es gab zwar Gespr\u00e4chsbedarf \u00fcber die Ausfl\u00fcge, weil er mehr auf Action steht und ich H\u00f6henangst habe, aber sonst&#8230; so harmonisch, es hat mich positiv \u00fcberrascht. Also&#8230; ich wei\u00df, es klingt jetzt kitschig, aber: Ich hab die richtige Entscheidung getroffen, es war das Beste, was wir machen konnten.<\/p>\n<p><em>Hattest du es dir anders vorgestellt?\u00a0<\/em><\/p>\n<p>Ich hab Angst gehabt, dass es so wird; dass es eben zu viel wird. Hier in Deutschland hat man seine Wohnung, jeder hat seine Arbeit, ist besch\u00e4ftigt und dort ist man schon 24 Stunden am Tag zusammen. Aber es war \u00fcberhaupt nicht zu viel: Man f\u00fchlt sich, als ob man frisch verliebt ist. Wie eine frisch verliebte Ehefrau <em>(kichert wieder vor sich hin).<\/em><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9642\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/img-20160906-wa0007-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?fit=1600%2C1600&amp;ssl=1\" data-orig-size=\"1600,1600\" data-comments-opened=\"1\" data-image-title=\"IMG-20160906-WA0007\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?fit=1020%2C1020&amp;ssl=1\" class=\"wp-image-9642 alignleft\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?resize=403%2C403&#038;ssl=1\" alt=\"\" width=\"403\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0007.jpg?resize=1024%2C1024&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 403px) 100vw, 403px\" \/><\/p>\n<p><em>Was gab es in Mexiko leckeres zu essen?<\/em><\/p>\n<p>Also, im Hotel mehr europ\u00e4isch. Jeden Tag war unter einem anderen Motto: Heute war mexikanisch, morgen italienisch, dann wieder international&#8230; einmal gab es mexikanische K\u00fcche mit einer richtig scharfen So\u00dfe, richtig mexikanisch eben; ich esse ja kein scharf, weil ich das nicht vertrage &#8211; Seba schon. Und sogar er\u00a0meinte, die So\u00dfe war unheimlich&#8230; Ich habe probiert und gleich nach dem Kellner gerufen; er soll sich beeilen, das Wasser holen, weil ich sonst fast gestorben w\u00e4re.<\/p>\n<p><em>Wie habt Ihr den langen Flug \u00fcberstanden (Stichwort Jetlag)? Wie viele Stunden seid ihr geflogen?<\/em><\/p>\n<p>Hin waren es dreizehn Stunden, zur\u00fcck waren es elf Stunden, glaube ich. Hin &#8211; war kein Problem, zur\u00fcck war ich so kaputt&#8230; Ich habe eine Woche gebraucht, um das wieder einzupendeln.<\/p>\n<p><em>Wieviel betrug die Zeitverschiebung?<\/em><\/p>\n<p>Sieben Stunden. Also, wenn hier in Deutschland neunzehn Uhr Abends ist, ist in Mexiko zw\u00f6lf Uhr mittags. Aber ich hatte das Gef\u00fchl, dass die Tage dort l\u00e4nger waren&#8230; obwohl es schneller dunkel war.<\/p>\n<p><em>K\u00f6nnte es daran gelegen haben, dass ihr weniger zu tun hattet? Weniger Pflichten?<\/em><\/p>\n<p>&#8230;k\u00f6nnte sein&#8230;<\/p>\n<p><em>Wie\u00a0die Menschen dort so sind, das hast du schon in den ersten S\u00e4tzen ein bisschen erz\u00e4hlt&#8230;<\/em><\/p>\n<p>Die\u00a0Welt\u00a0geschieht heute und wenn ich helfen kann, helfe ich. Umso weniger sie haben, umso mehr geben sie dir. Es ist wirklich so.\u00a0F\u00fcr eine H\u00e4ngematte zum Beispiel brauchen sie fast eine Woche, um sie anzufertigen. Und sie verkaufen die nur f\u00fcr drei\u00dfig Dollar&#8230; dabei arbeiten sie eine ganze Woche daf\u00fcr. Und das geht auch noch \u00fcber Zwischenh\u00e4ndler&#8230; Die Menschen haben nicht viel Geld. Und die meisten\u00a0leben\u00a0von\u00a0dem Trinkgeld, das du ihnen freiwillig gibst. Es ist schon sehr hart.<\/p>\n<p><em>Du hattest mir mal Bilder von den H\u00fctten gezeigt; wie die Menschen leben&#8230;<\/em><\/p>\n<p>Ja, da sind wir mal nach Villadollid gefahren und dieser Ort lag auf dem Weg dorthin; vom Bus aus konnte ich sehen, dass in so einem kleinen H\u00e4uschen, ein bisschen gr\u00f6\u00dfer als vier auf sechs Meter, bis zu zehn Leute wohnen.<\/p>\n<p><em>Man hat dann, glaube ich, gar nicht dieses Denken: meins, deins&#8230;<\/em><\/p>\n<p>&#8230;unseres. Und sie schlafen in H\u00e4ngematten.<\/p>\n<p><em>Das w\u00fcrde ich dort auch, wer wei\u00df, was da so alles am Boden herumkrabbelt.<\/em><\/p>\n<p>Ja, aber die k\u00f6nnen auch von der Decke auf deine H\u00e4ngematte\u00a0runterfallen.<\/p>\n<p><em>Hattet ihr dort Insekten? Spinnen oder \u00e4hnliches?<\/em><\/p>\n<p>Wir hatten nur Schnaken. Wir wurden nicht so oft gestochen, weil wir das Soventol benutzt haben, aber es war jetzt nicht soo super&#8230; Wenn du gestochen wurdest, wurden die Stiche richtig dick.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9643\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/img-20160906-wa0013-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0013.jpg?fit=1600%2C1200&amp;ssl=1\" data-orig-size=\"1600,1200\" data-comments-opened=\"1\" data-image-title=\"IMG-20160906-WA0013\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0013.jpg?fit=1020%2C765&amp;ssl=1\" class=\"alignnone wp-image-9643 size-full\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0013.jpg?resize=1020%2C765&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"765\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0013.jpg?w=1600&amp;ssl=1 1600w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0013.jpg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0013.jpg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0013.jpg?resize=1024%2C768&amp;ssl=1 1024w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p><em>Du hattest etwas von Shows erw\u00e4hnt &#8211; wo fanden die statt? Was wurde aufgef\u00fchrt? Wie waren denn die Eintrittspreise?<\/em><\/p>\n<p>Ach so, das war intern vom Hotel aus organisiert. Jede Show war wie so ne Fernsehsendung oder wie ein Musical, richtig cool gemacht. Einmal wurden die typischen T\u00e4nze aus verschiedenen Regionen Mexikos in\u00a0traditioneller Kleidung aufgef\u00fchrt; dann gab es einen Spiele-Abend oder Thema siebziger Jahre&#8230; Es war wirklich wie eine Fernsehsendung und du dachtest: Oh, es ist soweit, da geh ich jetzt sofort hin. Es hat sich immer gelohnt. Das Programm ging ca. eine Stunde, es wurde im Hotel direkt aufgef\u00fchrt. Es war wie eine gro\u00dfe Piazza mit einer aufgebauten B\u00fchne und dort waren gleichzeitig an die zwanzig Leute am tanzen; es war riesig!<\/p>\n<p><em>Welches Hotel war das?<\/em><\/p>\n<p>Viva maya, das geh\u00f6rt zu den Wyndham Hotels, eines davon gibt es auch hier in Mannheim.<\/p>\n<p><em>Und wie teuer?<\/em><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"9644\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/img-20160906-wa0005-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0005.jpg?fit=1200%2C1600&amp;ssl=1\" data-orig-size=\"1200,1600\" data-comments-opened=\"1\" data-image-title=\"IMG-20160906-WA0005\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0005.jpg?fit=768%2C1024&amp;ssl=1\" class=\"wp-image-9644 alignleft\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0005.jpg?resize=331%2C441&#038;ssl=1\" alt=\"\" width=\"331\" height=\"441\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0005.jpg?w=1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0005.jpg?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0005.jpg?resize=768%2C1024&amp;ssl=1 768w\" sizes=\"auto, (max-width: 331px) 100vw, 331px\" \/><\/p>\n<p>In Mexiko musst du f\u00fcr all inclusive so an die 60 $ US rechnen pro Person pro Nacht. Das Hotel hatte eigentlich nur drei Sterne, aber du hast dich gef\u00fchlt, als ob es zehn Sterne w\u00e4ren, wirklich. Wir hatten drei Riesen-Pools, direkte Strandlage, wei\u00dfer Sand, t\u00fcrkisenes Meer; du hast dich wie in einem reichen Viertel gef\u00fchlt. Wir hatten uns mal Fahrr\u00e4der ausgeliehen und sind damit die Stra\u00dfe entlang; man f\u00fchlt sich wie in Beverly Hills; richtig cool. \u00dcberall Palmen, die Sonne scheint&#8230; Ich bin sogar voll gerne Fahrrad gefahren. Nur die Fahrr\u00e4der waren ganz komisch, die Bremse war nicht am Lenker, sondern du hast r\u00fcckw\u00e4rts in die Pedale getreten und das war dann die Bremse; ich bin fast auf die Fresse gefallen.<\/p>\n<p><em>Das kenne ich noch aus Polen, bei uns war das auch so. Ich habe nur so fahren gelernt.<\/em><\/p>\n<p>War das nicht zu unsicher, einfach mit dem Fahrrad die Stra\u00dfen entlang zu fahren? Man h\u00f6rt so viele Geschichten \u00fcber Mexiko&#8230;<\/p>\n<p>Das h\u00e4ngt von der Gegend ab. Mexico City ist sehr gef\u00e4hrlich, hat man uns gesagt, aber dort, wo wir waren, war es sicher, du h\u00e4ttest da auch alleine spazieren k\u00f6nnen. Au\u00dfer diesen kleinen Drogen-Dealern, die ich erw\u00e4hnt hatte. Aber die haben dich auch nicht genervt.<\/p>\n<p>Wir waren am Strand, genie\u00dfen so die Sonne, dann kommt\u00a0einer auf uns zu und\u00a0fragt auf englisch: <em>Willst du Zigarren kaufen? Cigarrs, Cigarrs?<\/em> Und wir so: <em>Nein, danke.<\/em> Er fragt: <em>Italiener?<\/em> Wir: <em>Ja&#8230;\u00a0<\/em>Und dann fragt er uns auf italienisch, ob wir Gras kaufen wollen. Und ich guck den so an: \u00c4hm, neeein&#8230; Und der lacht sich kaputt&#8230;<\/p>\n<p>Dann waren wir auch an der fifth evenue spazieren, dort konntest du Taxi fahren f\u00fcr 90 Pesos (so ungef\u00e4hr 4,50 \u20ac sind das, nicht teuer), die Stra\u00dfe geht \u00fcber sechs Kilometer und ist ganz sch\u00f6n gemacht: Mit Cafes, Restaurants, Bars&#8230; musst du mal googeln, wirklich ganz sch\u00f6n gemacht. Jedenfalls wurden wir dort auch einfach mitten auf der Stra\u00dfe gefragt, ob wir Gras kaufen wollen.<\/p>\n<p><em>Also ein sch\u00f6ner Schein, dieses Vornehme, Edle und dann nebenbei solche Machenschaften&#8230;<\/em><\/p>\n<p>Ja, aber eben gut getarnt. Aber die waren alle freundlich, es gab nie Probleme. Wir k\u00f6nnen das nicht verstehen, wir sind hier aufgewachsen, aber dort&#8230; du musst k\u00e4mpfen, um zu \u00fcberleben, das ist einfach so.<\/p>\n<p>Also, Mexiko ist eine Reise wert, wirklich. Es ist eine Reise wert, einfach nur f\u00fcr sich genommen. Das klingt so weit weg&#8230; <em>Mexiko&#8230;<\/em> das klingt so weit weg und du denkst nur an <em>ta ta ta<\/em>, wenn du an Mexiko denkst; du denkst an diese kleinen Mexikaner, die dazu tanzen mit ihrem Sombrero und einen Kaktus im Bild &#8211; so stellst du dir Mexiko vor. Es ist \u00fcberhaupt nicht so. Manchmal machen die das wirklich; dass sie so tanzen, aber das ist einfach, womit sie dann ihr Geld verdienen.<\/p>\n<p>Aber wei\u00dft du, was mich fasziniert hat? Wir beschweren uns oft \u00fcber unsere Arbeit; dass wir nicht genug Geld kriegen und so weiter. Aber die Menschen dort machen den gr\u00f6\u00dften Dreck. Sie r\u00e4umen dir deine Teller weg und l\u00e4cheln dabei; aber nicht dieses aufgesetzte L\u00e4cheln, nein, sie sind wirklich freundlich. Sie fragen dich: Und? Hat&#8217;s geschmeckt, mein Freund? Sie fragen dich: Woher bist du? Sie denken nicht: Ich mach meine Arbeit und fertig, mich interessiert&#8217;s nicht, wer das ist und was er macht&#8230; Nein, sie fragen dich ernsthaft. Anfangs bist du zur\u00fcckhaltend, weil du nicht wei\u00dft, ob da nicht irgendwelche Hintergedanken sind, aber dann merkst du, dass sie alle so sind. Und dann gibst du <em>von dir aus<\/em> Trinkgeld. Weil du einfach so gl\u00fccklich bist, dass es vom Herzen kommt.\u00a0Und wenn du siehst, was die Menschen dort f\u00fcr einen Hungerlohn kriegen &#8211; das ist heftig.<\/p>\n<p>Nach so einer Reise wei\u00df man sein Leben mehr zu sch\u00e4tzen. Aber wei\u00dft du, der Mensch ist so: F\u00fcr eine Phase, okay, aber dann f\u00e4llt er wieder in seine Gewohnheiten zur\u00fcck, dann vergisst er das.<\/p>\n<p>Unser Fotograf war richtig traurig, dass wir gegangen sind. Wir hatten uns jeden Mittag miteinander unterhalten. Ich hatte ihn mal gefragt: Wie ist es mit deiner Arbeit? Ist es nicht anstrengend, sich jeden Tag dahin zu stellen, auf die Leute zuzugehen und zu fragen, ob sie ein Fotoshooting m\u00f6chten? Das stelle ich mir schon schwierig vor. Er sagte, ja, manchmal ist es nicht so einfach, wenn die Leute einen anmotzen, dass man sie in Ruhe lassen soll; aber dann gibt es Menschen, die so nett sind wie ihr und man kann \u00fcber alles reden, sich \u00fcber alles unterhalten.<\/p>\n<p><em>Ihr habt ja noch Kontakt, oder?<\/em><\/p>\n<p>Ja, aber in letzter Zeit nicht mehr so viel. Wenn ich was poste, dann liked er es, einfach so: Hallo, ich bin da, mich gibt&#8217;s noch.<\/p>\n<p>Man ist viel offener und entspannter, wenn man in Urlaub ist. Doch die Menschen in Mexiko sind nicht in Urlaub, sie machen ihre Arbeit und sind entspannt. Es ist wirklich so: sie machen ihre Arbeit; Zack, zack, zack, und denken sich: Wieso soll ich mich stressen? Morgen kann ich schon tot sein, wieso soll ich schlecht gelaunt sein? So denken sie.<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" data-services=\"facebook%7Cpinterest%7Ctumblr\" data-url=\"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/\" data-timestamp=\"1688070076\" data-backendurl=\"https:\/\/stefan-taege.de\/kasia\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2016%2F11%2F10%2Fmexico-the-best-honeymoon-ever%2F&text=Mexico%20%E2%80%93%20the%20best%20honeymoon%20ever%21\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2016%2F11%2F10%2Fmexico-the-best-honeymoon-ever%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span data-service=\"facebook\" style=\"color:#3b5998\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2016%2F11%2F10%2Fmexico-the-best-honeymoon-ever%2F&media=https%3A%2F%2Fstefan-taege.de%2Fkasia%2Fwp-content%2Fuploads%2F2016%2F11%2FIMG-20160906-WA0003-1-e1543021435602.jpg&description=Mexico%20%E2%80%93%20the%20best%20honeymoon%20ever%21\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span data-service=\"pinterest\" style=\"color:#cb2027\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button tumblr shariff-nocustomcolor\" style=\"background-color:#529ecc\"><a href=\"https:\/\/www.tumblr.com\/widgets\/share\/tool?posttype=link&canonicalUrl=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2016%2F11%2F10%2Fmexico-the-best-honeymoon-ever%2F&tags=stefan-taege.de\" title=\"Bei tumblr teilen\" aria-label=\"Bei tumblr teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#36465d; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#36465d\" d=\"M18 14l0 7.3c0 1.9 0 2.9 0.2 3.5 0.2 0.5 0.7 1.1 1.2 1.4 0.7 0.4 1.5 0.6 2.4 0.6 1.6 0 2.6-0.2 4.2-1.3v4.8c-1.4 0.6-2.6 1-3.7 1.3-1.1 0.3-2.3 0.4-3.6 0.4-1.5 0-2.3-0.2-3.4-0.6-1.1-0.4-2.1-0.9-2.9-1.6-0.8-0.7-1.3-1.4-1.7-2.2s-0.5-1.9-0.5-3.4v-11.2h-4.3v-4.5c1.3-0.4 2.7-1 3.6-1.8 0.9-0.8 1.6-1.7 2.2-2.7 0.5-1.1 0.9-2.4 1.1-4.1h5.2l0 8h8v6h-8z\"\/><\/svg><\/span><span data-service=\"tumblr\" style=\"color:#36465d\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2016%2F11%2F10%2Fmexico-the-best-honeymoon-ever%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button rss shariff-nocustomcolor\" style=\"background-color:#ff8c00\"><a href=\"https:\/\/stefan-taege.de\/kasia\/feed\/rss\/\" title=\"RSS-feed\" aria-label=\"RSS-feed\" role=\"button\" class=\"shariff-link\" style=\"; background-color:#fe9312; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#fe9312\" d=\"M4.3 23.5c-2.3 0-4.3 1.9-4.3 4.3 0 2.3 1.9 4.2 4.3 4.2 2.4 0 4.3-1.9 4.3-4.2 0-2.3-1.9-4.3-4.3-4.3zM0 10.9v6.1c4 0 7.7 1.6 10.6 4.4 2.8 2.8 4.4 6.6 4.4 10.6h6.2c0-11.7-9.5-21.1-21.1-21.1zM0 0v6.1c14.2 0 25.8 11.6 25.8 25.9h6.2c0-17.6-14.4-32-32-32z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2016%2F11%2F10%2Fmexico-the-best-honeymoon-ever%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Gef\u00fchrt mit Vanessa am 12 August 2016 Meine Apothekenfreundin Vanessa und Sebastiano, beide\u00a0erst k\u00fcrzlich\u00a0verm\u00e4hlt, verbrachten ihre Hochzeitsreise in Playa del &hellip; <\/p>\n","protected":false},"author":1,"featured_media":9646,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1336,1610],"tags":[1176,1175,921,1174],"class_list":["post-2639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mexiko","category-nordamerika","tag-flitterwochen","tag-honeymoon","tag-interview","tag-mexico"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mexico - the best honeymoon ever! - windrose.rocks<\/title>\n<meta name=\"description\" content=\"Du denkst nur an ta ta ta, wenn du an Mexiko denkst; du denkst an diese kleinen Mexikaner, die dazu tanzen mit ihrem Sombrero und einen Kaktus im Bild...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kasia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"13\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/\"},\"author\":{\"name\":\"Kasia\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\"},\"headline\":\"Mexico &#8211; the best honeymoon ever!\",\"datePublished\":\"2016-11-10T04:00:27+00:00\",\"dateModified\":\"2023-06-29T18:21:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/\"},\"wordCount\":2236,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1\",\"keywords\":[\"Flitterwochen\",\"Honeymoon\",\"Interview\",\"Mexico\"],\"articleSection\":[\"Mexiko\",\"Nordamerika\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/\",\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/\",\"name\":\"Mexico - the best honeymoon ever! - windrose.rocks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1\",\"datePublished\":\"2016-11-10T04:00:27+00:00\",\"dateModified\":\"2023-06-29T18:21:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\"},\"description\":\"Du denkst nur an ta ta ta, wenn du an Mexiko denkst; du denkst an diese kleinen Mexikaner, die dazu tanzen mit ihrem Sombrero und einen Kaktus im Bild...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2016\\\/11\\\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1\",\"width\":1600,\"height\":896},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2016\\\/11\\\/10\\\/mexico-the-best-honeymoon-ever\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mexico &#8211; the best honeymoon ever!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#website\",\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\",\"name\":\"windrose.rocks\",\"description\":\"Erz\u00e4hlungen einer Reisenden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\",\"name\":\"Kasia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"caption\":\"Kasia\"},\"description\":\"Hi, ich bin Kasia, die Stimme von \\\"windrose.rocks\\\" :-) Treibt Dich die Frage um, was sich denn alles jenseits der heimischen Couch verbirgt, bist Du rastlos und neugierig wie ich und sp\u00fcrst den Drang in Dir, in die Welt hinaus zu gehen? Dann tue es! Ich nehme Dich mit auf meine Reisen und lasse Dich hautnah das Unterwegs sein miterleben - in all seinen Facetten. Lass Dich inspirieren, komm mit mir und warte nicht l\u00e4nger, denn... die Welt ist so gro\u00df und wir sind so klein, und es gibt noch so viel zu sehen! Die Welt wartet auf uns.\",\"sameAs\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\"],\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/author\\\/kasia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mexico - the best honeymoon ever! - windrose.rocks","description":"Du denkst nur an ta ta ta, wenn du an Mexiko denkst; du denkst an diese kleinen Mexikaner, die dazu tanzen mit ihrem Sombrero und einen Kaktus im Bild...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/","twitter_misc":{"Verfasst von":"Kasia","Gesch\u00e4tzte Lesezeit":"13\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#article","isPartOf":{"@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/"},"author":{"name":"Kasia","@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f"},"headline":"Mexico &#8211; the best honeymoon ever!","datePublished":"2016-11-10T04:00:27+00:00","dateModified":"2023-06-29T18:21:16+00:00","mainEntityOfPage":{"@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/"},"wordCount":2236,"commentCount":0,"image":{"@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1","keywords":["Flitterwochen","Honeymoon","Interview","Mexico"],"articleSection":["Mexiko","Nordamerika"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/","url":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/","name":"Mexico - the best honeymoon ever! - windrose.rocks","isPartOf":{"@id":"https:\/\/stefan-taege.de\/kasia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#primaryimage"},"image":{"@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1","datePublished":"2016-11-10T04:00:27+00:00","dateModified":"2023-06-29T18:21:16+00:00","author":{"@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f"},"description":"Du denkst nur an ta ta ta, wenn du an Mexiko denkst; du denkst an diese kleinen Mexikaner, die dazu tanzen mit ihrem Sombrero und einen Kaktus im Bild...","breadcrumb":{"@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#primaryimage","url":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1","contentUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1","width":1600,"height":896},{"@type":"BreadcrumbList","@id":"https:\/\/stefan-taege.de\/kasia\/2016\/11\/10\/mexico-the-best-honeymoon-ever\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stefan-taege.de\/kasia\/"},{"@type":"ListItem","position":2,"name":"Mexico &#8211; the best honeymoon ever!"}]},{"@type":"WebSite","@id":"https:\/\/stefan-taege.de\/kasia\/#website","url":"https:\/\/stefan-taege.de\/kasia\/","name":"windrose.rocks","description":"Erz\u00e4hlungen einer Reisenden","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stefan-taege.de\/kasia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f","name":"Kasia","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","caption":"Kasia"},"description":"Hi, ich bin Kasia, die Stimme von \"windrose.rocks\" :-) Treibt Dich die Frage um, was sich denn alles jenseits der heimischen Couch verbirgt, bist Du rastlos und neugierig wie ich und sp\u00fcrst den Drang in Dir, in die Welt hinaus zu gehen? Dann tue es! Ich nehme Dich mit auf meine Reisen und lasse Dich hautnah das Unterwegs sein miterleben - in all seinen Facetten. Lass Dich inspirieren, komm mit mir und warte nicht l\u00e4nger, denn... die Welt ist so gro\u00df und wir sind so klein, und es gibt noch so viel zu sehen! Die Welt wartet auf uns.","sameAs":["https:\/\/stefan-taege.de\/kasia\/"],"url":"https:\/\/stefan-taege.de\/kasia\/author\/kasia\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/p7Ku1E-Gz","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2016\/11\/IMG-20160906-WA0003-1-e1543021435602.jpg?fit=1600%2C896&ssl=1","_links":{"self":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/2639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/comments?post=2639"}],"version-history":[{"count":10,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/2639\/revisions"}],"predecessor-version":[{"id":26135,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/2639\/revisions\/26135"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/media\/9646"}],"wp:attachment":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/media?parent=2639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/categories?post=2639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/tags?post=2639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}