{"id":23996,"date":"2025-10-05T08:17:27","date_gmt":"2025-10-05T06:17:27","guid":{"rendered":"http:\/\/stefan-taege.de\/kasia\/?p=23996"},"modified":"2025-09-21T20:48:34","modified_gmt":"2025-09-21T18:48:34","slug":"so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik","status":"publish","type":"post","link":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/","title":{"rendered":"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik"},"content":{"rendered":"<p><em>Dieser Artikel erschien bereits am 04.01.2020<\/em><\/p>\n<p>Silvester in Reykjavik: schon am Morgen startet der Silvesterlauf in Verkleidung, abends gibt es gro\u00dfe Lagerfeuer und das Feuerwerk danach hat es in sich\u2026<!--more--><\/p>\n<p>In Island gibt es viele Legenden und Br\u00e4uche, die mir bisher unbekannt waren. Da das Land ziemlich ab vom Schuss gelegen ist und lange Zeit recht abgeschieden war, hat sich vieles davon bis heute erhalten und die Einfl\u00fcsse der restlichen Welt halten nur langsam Einzug auf die raue Insel. Auch einen nennenswerten Tourismus gibt es in Island so gesehen erst seit etwa zehn Jahren.<\/p>\n<p>So kommt es auch, dass Weihnachtsm\u00e4rkte in der Adventszeit zwar vorhanden, aber doch sehr anders und bei weitem nicht so umfangreich sind wie bei uns. Auch der Silvestertag und -abend hat seine eigenen, besonderen Traditionen. Wie ich in Island ins Neue Jahr gekommen bin? Das kannst du hier nachlesen ?<\/p>\n<p>&nbsp;<\/p>\n<h3>Dem Neuen Jahr entgegen laufen \u2013 Der IR\u2019s New Years Eve Run<\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25383\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_120311\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?fit=2048%2C1152&amp;ssl=1\" data-orig-size=\"2048,1152\" data-comments-opened=\"1\" data-image-title=\"20191231_120311\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?fit=1020%2C574&amp;ssl=1\" class=\"alignnone size-full wp-image-25383\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?resize=1020%2C574&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"574\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120311.jpg?resize=107%2C60&amp;ssl=1 107w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Die Isl\u00e4nder sind zum gro\u00dfen Teil ein sportbegeistertes Volk. Und sie schl\u00fcrfen nicht gem\u00fctlich mit Wollsocken und M\u00fctze ins Neue Jahr hinein, nein, sie rennen. Mit all der Begeisterung, die man bei kaltem und ungem\u00fctlichen Wetter aufbringen kann. Jedes Jahr am Vormittag des Silvestertages gibt es den traditionellen New Years Eve Run, der p\u00fcnktlich um zw\u00f6lf Uhr startet. Mit diesem zehn Kilometer langem Lauf wird der Start ins Neue Jahr gefeiert.<\/p>\n<p>Das Event ist mit rund 2000 Teilnehmern einer der gr\u00f6\u00dften isl\u00e4ndischen Laufveranstaltungen und f\u00fcr alle Altersgruppen geeignet. Die Tradition der Silvesterl\u00e4ufe ist kein eigens isl\u00e4ndischer Brauch, sondern zieht sich wie ein rotes Band rund um den Globus. Es gibt Silvesterl\u00e4ufe \u00fcberall auf der Welt, doch in Reykjavik gibt es dabei eine Besonderheit: viele Teilnehmer sind verkleidet und tragen abgefahrene Kost\u00fcme und so, kost\u00fcmiert und in gro\u00dfartiger Laune rennen sie dem Neuen Jahr entgegen.<\/p>\n<p>Und das will ich mir nicht entgehen lassen.<\/p>\n<p>Das Neue Jahr beginnt regnerisch. Nachdem ich mich am fr\u00fchen Morgen ab acht Uhr schwimmend an der allgemeinen Sportbegeisterung beteiligt habe, mache ich mich nun auf zur Harpa Konzerthalle, wo der Lauf um Punkt zw\u00f6lf beginnen sollte. Unterwegs versuche ich noch, ein Essen abzugreifen, was nicht so einfach ist angesichts dessen, dass viele Lokale erst ab Mittag \u00f6ffnen. Schlie\u00dflich schnappe ich mir bei meinem Lieblingsb\u00e4cker eines der sagenhaften Pastries, die auf der Zunge zergehen, und gehe weiter, um p\u00fcnktlich zum Beginn des Ereignisses vor Ort zu sein.<\/p>\n<p>Einige Menschen sind bereits an diesem Morgen in der Stadt unterwegs, erledigen die letzten Eink\u00e4ufe, ehe die L\u00e4den dicht machen und man nichts mehr bekommt. Einige m\u00fcssen wohl auch arbeiten, wie bei uns auch. Es ist inzwischen hell geworden, doch ein feiner Nieselregen ergie\u00dft sich weiterhin vom Himmel, mal st\u00e4rker und mal schw\u00e4cher. Der Himmel selbst ist bedeckt und trotz des aufkommenden Tageslichts (das ja in Island zu der Jahreszeit so eine Sache f\u00fcr sich ist\u2026) leuchtet weiterhin die Stra\u00dfenbeleuchtung. Speziell bei einem solchen Wetter wirken die Tage wie eine einzige Blaue Stunde, die niemals endet. Tr\u00fcb, energieraubend, kalt. Da habt ihr euch ja das perfekte Wetter f\u00fcr euren Lauf ausgesucht, denke ich mir und rechne in diesem Jahr f\u00fcr den New Years Run mit nicht wirklich viel Aufkommen.<\/p>\n<p>Ich bin dick eingem\u00fcmmelt in meine M\u00fctze, meinen Wollschal und unter der Kapuze sieht die Welt f\u00fcr mich gar nicht mehr so kalt aus. Die Reste des s\u00fc\u00dfen Geb\u00e4cks verschwinden klebrig in meinem Mund. Langsam n\u00e4here ich mich der Harper Konzerthalle. Hier beginnen die Menschen bereits, zusammen zu kommen. Schon von weitem dringt zu mir laute Musik, die aus den Boxen kommt und Energie, Sportsgeist und Begeisterung vermittelt.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25384\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_112341\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?fit=2048%2C1152&amp;ssl=1\" data-orig-size=\"2048,1152\" data-comments-opened=\"1\" data-image-title=\"20191231_112341\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?fit=1020%2C574&amp;ssl=1\" class=\"alignnone size-full wp-image-25384\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?resize=1020%2C574&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"574\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_112341.jpg?resize=107%2C60&amp;ssl=1 107w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Und ich sehe, wie sehr ich mich geirrt habe, denn vor und speziell in der Konzerthalle selbst ist es voll und es kommen immer neue L\u00e4ufer dazu. Der laute Beat aus den Boxen l\u00e4sst keine M\u00fcdigkeit oder schlechte Laune aufkommen und der Isl\u00e4nder w\u00e4re kein Isl\u00e4nder, w\u00fcrde er sich gro\u00df von schlechtem Wetter beeindrucken lassen \u2013 das h\u00e4tte ich besser wissen sollen. Die Menschen lachen, sie w\u00e4rmen sich auf oder schw\u00e4tzen miteinander, es treffen sich Freunde und Teams, Erinnerungsfotos werden geschossen.<\/p>\n<p>Und fast alle L\u00e4ufer tragen fancy Kost\u00fcme, seien es Schneem\u00e4nner aus \u201eDie Eisk\u00f6nigin\u201c, Spiderman, die Schl\u00fcmpfe oder einfach ganz undefinierbare, abgefahrene Sachen. Ich stehe inmitten von all dem Trubel und sp\u00fcre, wie sich die Begeisterung auf mich \u00fcbertr\u00e4gt. Also, ihr seid schon ein bisschen verr\u00fcckt, w\u00fcrde ich den Menschen am liebsten zurufen \u2013 ein kleines bisschen nur, aber das ist okay. Ich liebe eure Verr\u00fccktheit, ich liebe eure Kost\u00fcme und eure Begeisterung. Die Stimmung ist gro\u00dfartig.<\/p>\n<p>Auf einer kleinen B\u00fchne steht eine Animateurin, die zum Aufw\u00e4rmen dr\u00e4ngt. Rund um die B\u00fchne versammelt sich nun eine kleine Gruppe verkleideter L\u00e4ufer und beginnt, sich aufzuw\u00e4rmen. Das sieht schon skurril aus. Ich dr\u00fccke mich an die Glaswand der Halle, sp\u00e4he ab und zu nach drinnen, wo es gestopfte voll ist und von verkleideten L\u00e4ufern nur so wimmelt. Die Halle ist der Treffpunkt der L\u00e4ufer, hier kann man sich umziehen oder eine Kleinigkeit trinken oder auch im Warmen abwarten, bis der Lauf startet \u2013 nicht dass hier irgend jemandem die K\u00e4lte etwas ausgemacht h\u00e4tte.<\/p>\n<div style=\"width: 1020px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-23996-1\" width=\"1020\" height=\"574\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_113524.mp4?_=1\" \/><a href=\"https:\/\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_113524.mp4\">https:\/\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_113524.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>Der Zeiger r\u00fcckt immer n\u00e4her an die zw\u00f6lf heran. Und irgendwann ist es so, als h\u00e4tte jemand ein unsichtbares Zeichen gegeben \u2013 so ab zehn vor zw\u00f6lf beginnen die L\u00e4ufer, sich zur Startlinie zu begeben. Ich habe noch das Gl\u00fcck, im letzten Moment ein Foto von einer \u201eKiss-Band\u201c zu ergattern \u2013 das musste einfach sein, die Kost\u00fcme der Frauengruppe sind gro\u00dfartig.<\/p>\n<p>Nun werden auch die letzten aufgerufen, sich zur Startlinie zu begeben. Schlagartig leert sich die Halle. Es sind bereits Stra\u00dfen abgesperrt worden und die Startbahn markiert und Polizeifahrzeuge begleiten den Lauf und fahren vorneweg. Noch nicht, nat\u00fcrlich. Noch wartet alles auf den Startschuss.<\/p>\n<p>Die L\u00e4ufer sind in Startposition und am Stra\u00dfenrand haben sich bereits ein paar Touristen mit ihren Kameras positioniert, doch es sind nur wenige, der isl\u00e4ndische Silvesterlauf scheint vielen noch ein Geheimtipp zu sein.<\/p>\n<p>Der Countdown l\u00e4uft, eine Stimme aus dem Lautsprecher z\u00e4hlt herunter. Acht\u2026 f\u00fcnf\u2026 drei\u2026 eins\u2026 und los! Der Schuss f\u00e4llt und sie laufen los. Unz\u00e4hlige bunte Verkleidungen ziehen sportlich an mir vorbei, die Zuschauer jubeln mit. Was f\u00fcr eine Art, ins Neue Jahr zu gehen!<\/p>\n<div style=\"width: 1020px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-23996-2\" width=\"1020\" height=\"574\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120101.mp4?_=2\" \/><a href=\"https:\/\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120101.mp4\">https:\/\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120101.mp4<\/a><\/video><\/div>\n<p>&nbsp;<\/p>\n<p>Als die L\u00e4ufer vorbei gezogen sind, zerstreuen sich langsam die wenigen Zuschauer. Vor der Halle ist es nun leer, die Startmarkierung wird wieder abger\u00e4umt. Ich schlendere langsam wieder ins Zentrum von Reykjavik zur\u00fcck, wo ich sp\u00e4ter in einem Lokal die besten Fish &amp; Chips meines Lebens esse und \u00fcber den Lauf sinniere.<\/p>\n<p>Also, leicht irre sind die Isl\u00e4nder schon, denke ich mir mit einem kleinen Grinsen im Gesicht \u2013 leicht irre, aber auf eine gute Weise. Und ich beginne, den zartesten Fisch meines Lebens kauend, die Vorz\u00fcge eines solchen Starts ins Neujahr zu sehen.<\/p>\n<p>Zum einem ist da der Ehrgeiz. Der bestandene Lauf hilft dabei, feste Ziele zu setzen und st\u00e4rkt das Vertrauen in sich, sie auch zu erreichen. Es ist eine Challenge, die auf viele weitere Herausforderungen vorbereitet, die das Leben stellt und die gemeistert werden wollen. Der L\u00e4ufer wei\u00df \u2013 ich habe den Lauf absolviert, alles andere schaffe ich auch noch.<\/p>\n<p>Dann ist da die Gemeinschaft.<\/p>\n<p>Man trifft Freunde, Bekannte, Gleichgesinnte, die genauso verr\u00fcckt und begeistert sind wie man selbst. Die Stimmung ist gro\u00dfartig. Und bei allem Ehrgeiz und Zielsetzung erinnern die bunten, ausgefallenen Kost\u00fcme daran, das Leben nicht zu verbissen zu sehen und niemals den Humor und den Spa\u00df an der Sache zu verlieren. Wie ich finde, ist es die perfekte Mischung, um das Neue Jahr anzugehen.<\/p>\n<figure id=\"attachment_25387\" aria-describedby=\"caption-attachment-25387\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25387\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_115530\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?fit=2048%2C1152&amp;ssl=1\" data-orig-size=\"2048,1152\" data-comments-opened=\"1\" data-image-title=\"20191231_115530\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?fit=1020%2C574&amp;ssl=1\" class=\"wp-image-25387 size-full\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?resize=1020%2C574&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"574\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115530.jpg?resize=107%2C60&amp;ssl=1 107w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-25387\" class=\"wp-caption-text\">Gro\u00dfartige Kost\u00fcme<\/figcaption><\/figure>\n<figure id=\"attachment_25388\" aria-describedby=\"caption-attachment-25388\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25388\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_115632\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?fit=2048%2C1152&amp;ssl=1\" data-orig-size=\"2048,1152\" data-comments-opened=\"1\" data-image-title=\"20191231_115632\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?fit=1020%2C574&amp;ssl=1\" class=\"wp-image-25388 size-full\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?resize=1020%2C574&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"574\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_115632.jpg?resize=107%2C60&amp;ssl=1 107w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-25388\" class=\"wp-caption-text\">Die L\u00e4ufer nehmen Aufstellung<\/figcaption><\/figure>\n<figure id=\"attachment_25389\" aria-describedby=\"caption-attachment-25389\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25389\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_120240\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?fit=2048%2C1152&amp;ssl=1\" data-orig-size=\"2048,1152\" data-comments-opened=\"1\" data-image-title=\"20191231_120240\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?fit=1020%2C574&amp;ssl=1\" class=\"wp-image-25389 size-full\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?resize=1020%2C574&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"574\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?resize=1024%2C576&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?resize=768%2C432&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?resize=1536%2C864&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_120240.jpg?resize=107%2C60&amp;ssl=1 107w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-25389\" class=\"wp-caption-text\">Der Schuss f\u00e4llt&#8230; Und los gehts!<\/figcaption><\/figure>\n<p>Der Lauf dauert etwa bis 13:30 Uhr. Danach versammeln sich die verschwitzten, gl\u00fccklichen Teilnehmer wieder an der Harper Halle, um drinnen voller Gl\u00fcck und Endorphine die anschlie\u00dfende Party zu feiern. Die \u00fcberlasse ich ihnen, da muss ich nicht dabei sein. Ich bezahle den Fisch und die Chips und schlendere zur\u00fcck zum Hostel.<\/p>\n<p>&nbsp;<\/p>\n<h3>Die \u00c1ram\u00f3tabrenna \u2013 Reykjaviks Silvesterlagerfeuer<\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25390\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_205257\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_205257\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25390\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205257.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Eine weitere, sch\u00f6ne Tradition am Vorabend des Neuen Jahres sind die gro\u00dfen Feuer, die \u00fcberall in der Stadt an den Str\u00e4nden von Reykjavik entz\u00fcndet werden. Egal bei welchem Wetter, es wird gem\u00fctlich und warm und die Menschen r\u00fccken n\u00e4her zusammen, lassen das Jahr Revue passieren.<\/p>\n<p>Und so habe ich in diesem Jahr die Aramotabrenna in Reykjavik erlebt:<\/p>\n<figure id=\"attachment_25391\" aria-describedby=\"caption-attachment-25391\" style=\"width: 182px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25391\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_122038\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_122038-e1586671739739.jpg?fit=373%2C1121&amp;ssl=1\" data-orig-size=\"373,1121\" data-comments-opened=\"1\" data-image-title=\"20191231_122038\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_122038-e1586671739739.jpg?fit=341%2C1024&amp;ssl=1\" class=\"wp-image-25391\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_122038-e1586671739739.jpg?resize=182%2C547&#038;ssl=1\" alt=\"\" width=\"182\" height=\"547\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_122038-e1586671739739.jpg?w=373&amp;ssl=1 373w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_122038-e1586671739739.jpg?resize=100%2C300&amp;ssl=1 100w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_122038-e1586671739739.jpg?resize=341%2C1024&amp;ssl=1 341w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_122038-e1586671739739.jpg?resize=20%2C60&amp;ssl=1 20w\" sizes=\"auto, (max-width: 182px) 100vw, 182px\" \/><figcaption id=\"caption-attachment-25391\" class=\"wp-caption-text\">Der isl\u00e4ndische Sommer ist ein Witz \u2013 nun, da k\u00f6nnte war dran sein, denn die Sommer in Island werden im Durchschnitt selten w\u00e4rmer als 16 bis 18 Grad.<\/figcaption><\/figure>\n<p>Gegen Nachmittag nach dem Silvesterlauf wird es ruhig in der Stadt. Die Menschen erledigen letzte Eink\u00e4ufe und ich nutze die Zeit, um im Hostel ein kleines Schl\u00e4fchen zu halten. Heute, in der Silvesternacht, werde ich kein Auge zutun, denn es ist gleichzeitig die Nacht \u2013 oder der Morgen \u2013 meiner Abreise. Momentan nieselt es vor sich hin und drau\u00dfen gibt es nicht viel zu holen. Kasia macht ein st\u00e4rkendes Nickerchen.<\/p>\n<p>Gegen acht verlasse ich \u00e4u\u00dferst schlecht gelaunt das Hostel. Bei meinem Transfer zur\u00fcck zum Flughafen hatte sich ein Fehler eingeschlichen und es wurde ein falscher Abholort ins System eingegeben. Der Anbieter ist trotz eines 24h Services nicht erreichbar und ich wei\u00df nicht wirklich, wo ich mich heute Nacht um vier einfinden soll. So laufe ich vor mich hin durch die dunklen Stra\u00dfen auf der Suche nach den gro\u00dfen Silvesterfeuern, den Aramotabrenna, die an mehreren Stellen an den K\u00fcsten Reykjaviks entz\u00fcndet werden.<\/p>\n<p>Dabei bewundere ich die vielen, festlichen Dekorationen, die L\u00e4mpchen und Lichter, mit denen die H\u00e4user, B\u00e4ume und Z\u00e4une geschm\u00fcckt sind. Zumindest regnet es nicht, denke ich mir und schaue hoffnungsvoll zum Himmel hinauf. Wie auf Kommando beginnt es einen Augenblick sp\u00e4ter zu nieseln. Ist das euer Ernst?<\/p>\n<p>Ich gebe es auf, mich selbst moralisch aufzubauen. Da gibt es jetzt nichts mehr sch\u00f6n zu reden, es ist Silvesterabend und ich laufe alleine drau\u00dfen im Regen die dunklen Stra\u00dfen und glaube, die isl\u00e4ndischen Elfen m\u00f6gen mich gerade nicht besonders. Was habe ich mir nur dabei gedacht. Ja, es gibt sie, diese Augenblicke, in denen ich als Alleinreisende f\u00fcr einen kurzen Moment alles infrage stelle und mich frage, was das ganze eigentlich soll. Ich h\u00e4tte diese Zeit in den Armen meines Liebsten verbringen k\u00f6nnen, der gerade auf F\u00f6hr herumgondelt. Aber F\u00f6hr? Neee\u2026 All die Erlebnisse verpassen, die ich hier hatte? Dann doch lieber Island.<\/p>\n<p>Doch schnell lenken andere Dinge meine Aufmerksamkeit von den kleinen Problemchen ab. Ich bin fatalistisch und wenn alles gerade so richtig schlecht f\u00fcr mich l\u00e4uft, dann ist es der perfekte Moment, um sich zu entspannen, denn dann kann es ja nur besser werden.<\/p>\n<p>Und wenn du denkst, es geht nicht mehr, kommt irgendwo ein Lichtlein her\u2026 Und hier kommt es tats\u00e4chlich, und zwar in Form kleiner, brennender Kerzen, die vor vielen T\u00fcren stehen und in die Nacht hinein leuchten und deren Bedeutung mir zu diesem Zeitpunkt noch verborgen ist. Doch die Silvesternacht in Island ist magisch und da geschehen viele Wunder. Habe ich mir sagen lassen.<\/p>\n<p>Die Aramotabrenna sind an gleich mehreren Orten in Reykjavik zu finden; gleich neun solcher Feuer werden in diesem Jahr entz\u00fcndet. Unter folgendem Link findest du eine Karte mit den aktuellen Standorten der j\u00e4hrlichen Aramotabrenna, so dass sich bestimmt auch eines in deiner N\u00e4he finden l\u00e4sst.<\/p>\n<p>Von meinem Hostel aus befindet sich die n\u00e4chstgelegene Feuerstelle an der Aegissida Stra\u00dfe, s\u00fcdwestlich von der Altstadt. Lange Zeit gehe ich alleine durch die leeren, dunklen Stra\u00dfen. Immer wieder werden Feuerwerke entz\u00fcndet, lange vor der eigentlichen Zeit.<\/p>\n<figure id=\"attachment_25393\" aria-describedby=\"caption-attachment-25393\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25393\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_194444\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?fit=2048%2C2048&amp;ssl=1\" data-orig-size=\"2048,2048\" data-comments-opened=\"1\" data-image-title=\"20191231_194444\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Alles ist festlich geschm\u00fcckt, doch die Stra\u00dfen sind leer in der n\u00e4chtlichen Stille&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?fit=1020%2C1020&amp;ssl=1\" class=\"size-full wp-image-25393\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=1020%2C1020&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"1020\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=1536%2C1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=435%2C435&amp;ssl=1 435w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194444.jpg?resize=60%2C60&amp;ssl=1 60w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-25393\" class=\"wp-caption-text\">Alles ist festlich geschm\u00fcckt, doch die Stra\u00dfen sind leer in der n\u00e4chtlichen Stille<\/figcaption><\/figure>\n<figure id=\"attachment_25394\" aria-describedby=\"caption-attachment-25394\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25394\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_194810\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_194810\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;In Hauseing\u00e4ngen brennen kleine Lichtlein&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?fit=1020%2C496&amp;ssl=1\" class=\"size-full wp-image-25394\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_194810.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-25394\" class=\"wp-caption-text\">In Hauseing\u00e4ngen brennen kleine Lichtlein<\/figcaption><\/figure>\n<p>Das geht schon seit mindestens drei Tagen so, immer wieder h\u00f6rt man Feuerwerksk\u00f6rper in der ganzen Stadt. Ansonsten liegen die nassen Stra\u00dfen still und gl\u00e4nzend vor mir da und die ganze Stadt leuchte festlich in der Dunkelheit der Nacht.<\/p>\n<p>Doch je n\u00e4her ich meinem Ziel komme, umso mehr Menschen finden sich um mich herum ein. Wenn du auf der Suche nach einem Ort, einem Event bist und nicht genau wei\u00dft, wo es stattfindet, merkst du trotzdem sehr schnell, ob du richtig bist. Wie Geister, wie ferngesteuerter Zombies sch\u00e4len sich immer weitere Gestalten aus dem Dunkel ins Licht der Stra\u00dfenlaternen und gehen langsam, in einstimmigem Schweigen, in die gleiche Richtung wie ich.<\/p>\n<p>Schlie\u00dflich, an einer Abzweigung zweier Stra\u00dfen, gibt es nur diese eine Option: von links peitscht der Wind den Regen heran und da, auf der rechten Seite, leuchten schon die Blaulichter der Feuerwehrautos. Genau dorthin wendet sich nun die stille Menschenmenge.<\/p>\n<figure id=\"attachment_25396\" aria-describedby=\"caption-attachment-25396\" style=\"width: 2048px\" class=\"wp-caption alignnone\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25396\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_202251\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_202251\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Der Holzhaufen steht bereit, die Menschenmenge wartet&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?fit=1020%2C496&amp;ssl=1\" class=\"size-full wp-image-25396\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_202251.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><figcaption id=\"caption-attachment-25396\" class=\"wp-caption-text\">Der Holzhaufen steht bereit, die Menschenmenge wartet<\/figcaption><\/figure>\n<p>Als ich vor Ort ankomme, merke ich, dass ich keineswegs zu sp\u00e4t bin, denn der gro\u00dfe, aus Sperrm\u00fcll errichtete Scheiterhaufen ist noch nicht entz\u00fcndet. Da es auf Island kaum B\u00e4ume gibt (sprich, Pflanzen, die die Bezeichnung Baum verdienen\u2026) und Holz entsprechend teuer ist, werden f\u00fcr die Feuer ausrangierte Sperrm\u00fcll-St\u00fccke verwendet, die, wie es scheint, eigens f\u00fcr diesen Anlass das ganze Jahr \u00fcber gesammelt und aufgehoben werden. Es ist die perfekte Entsorgung, das sch\u00f6ne, j\u00e4hrliche Feuerchen. Warum gutes Holz verschwenden.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25397\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_204126-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?fit=996%2C2048&amp;ssl=1\" data-orig-size=\"996,2048\" data-comments-opened=\"1\" data-image-title=\"20191231_204126\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?fit=498%2C1024&amp;ssl=1\" class=\"wp-image-25397 alignleft\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?resize=196%2C403&#038;ssl=1\" alt=\"\" width=\"196\" height=\"403\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?w=996&amp;ssl=1 996w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?resize=146%2C300&amp;ssl=1 146w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?resize=498%2C1024&amp;ssl=1 498w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?resize=768%2C1579&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?resize=747%2C1536&amp;ssl=1 747w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204126.jpg?resize=29%2C60&amp;ssl=1 29w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/p>\n<p>Ich bin nicht zu sp\u00e4t, doch auch keineswegs zu fr\u00fch; ich komme gerade zur rechten Zeit, denn immer mehr Menschen str\u00f6men im Regen zu dem Holzhaufen und platzieren sich in einem weiten Bogen um ihn herum. Das Ganze hat schon etwas von einer Prozession, von einer stillen Urteilssprechung, die Kapuzen auf den K\u00f6pfen der Leute und die im Schatten liegenden Gesichter vervollst\u00e4ndigen noch das Bild. Alles wartet schweigend darauf, was als n\u00e4chstes passiert. Doch es ist eine freudige Erwartung. Die Gesichter der Kinder gl\u00fchen vor Anspannung. Es ist gleich halb neun am Abend.<\/p>\n<p>Die Feuerwehr entz\u00fcndet den Haufen Holz und als der erste Funke gl\u00fcht, l\u00f6st sich die Anspannung. Die Menschen kommen enger um das Feuer herum, es wird applaudiert und der Begeisterung kundgetan. Das Lagerfeuer brennt.<\/p>\n<p>Doch damit ist die Arbeit f\u00fcr die Feuerwehrm\u00e4nner noch lange nicht getan, ganz im Gegenteil. Der Holzhaufen ist vom Regen durchweicht. Gerade jetzt setzen die M\u00e4nner alles daran, um das kleine Feuerchen, das in dem nassen Haufen brennt, am Leben zu erhalten. Doch das stellt sich als gar nicht so einfach heraus. Immer wieder wird Brennstoff (Benzin? Ich habe keine Ahnung, ich bin Laie\u2026) in und neben das Feuer gesch\u00fcttet und das Holz von anderen Seiten angez\u00fcndet.<\/p>\n<p>Doch zun\u00e4chst will das Feuer gar nicht richtig \u00fcbergreifen. Und wie \u00fcberall auf der Welt, so wissen auch hier viele der Umherstehenden, woran das liegen oder nicht liegen k\u00f6nnte. Es wird viel kommentiert und die englisch- und polnischsprachigen Bemerkungen kann ich zumindest verstehen.<\/p>\n<p>Doch schlie\u00dflich ist der Bahn gebrochen und die Flammen schie\u00dfen nach oben und \u00fcbernehmen die Mitte. Jetzt brennt der Holzhaufen lichterloh. Der Geruch nach Holzofengrill weht mit den Flammen zu uns her\u00fcber.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25399\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_205124\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_205124\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25399\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205124.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25400\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_204411-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?fit=2048%2C1154&amp;ssl=1\" data-orig-size=\"2048,1154\" data-comments-opened=\"1\" data-image-title=\"20191231_204411\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?fit=1020%2C575&amp;ssl=1\" class=\"alignnone size-full wp-image-25400\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?resize=1020%2C575&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"575\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?resize=300%2C169&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?resize=1024%2C577&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?resize=768%2C433&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?resize=1536%2C866&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_204411.jpg?resize=106%2C60&amp;ssl=1 106w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/> <img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25401\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_205547\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_205547\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25401\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_205547.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Die Menschen freuen sich. Sofort ver\u00e4ndert sich die Stimmung und so etwas wie Feierlaune kommt auf. Das hei\u00dfe Feuer w\u00e4rmt die Gesichter und h\u00e4lt, zumindest von einer Seite, die K\u00e4lte und den Regen fern, der sich seitlich heranzupirschen versucht. Die Witterung auf Island ist rau und ich sehe immer wieder mit Begeisterung, wie sehr die Menschen hier drauf pfeifen.<\/p>\n<p>Der Rauch zieht leider in Richtung Stadt, doch das schm\u00e4lert die Begeisterung nicht. Kerzen und k\u00fcnstliche Feuer werden entz\u00fcndet, viele der Teilnehmer holen vorher eingekauftes Bier aus den Taschen. Ganze Familien machen Selfies oder lassen sich zusammen am Lagerfeuer fotografieren. Das ist einer der Augenblicke, in denen ich, ungeachtet der ganzen Sache mit dem alleine Reisen, doch jemanden an meiner Seite gehabt h\u00e4tte. Ich frage ein hinter mir stehendes polnisches Paar, das mit zwei kleinen Kindern da ist, nach einem Foto.<\/p>\n<p>Der Regen h\u00f6rt nicht auf und trotz der Hitze an meinem Gesicht sp\u00fcre ich, wie meine Jacke langsam durchweicht. Das Wetter ist so unberechenbar hier. Erst klarer Himmel, dann ganz feine Regenschwaden, die von der Seite ankommen, eine ganz feine Gicht, der man nicht entkommen kann. Ich versuche, etwas n\u00e4her ans Feuer zu r\u00fccken. Es riecht nach brennendem Holz und Rauch. Schwarze Rauchwolken st\u00f6bern in den Himmel und hei\u00df gl\u00fchende Funken tanzen in den rauchgrauen Himmel.<\/p>\n<p>Viele der Menschen sind jetzt in Partylaune. Auch hier werden bereits Raketen entz\u00fcndet, die die Nacht mit glei\u00dfendem Licht erhellen. Viele der j\u00fcngeren Leute tragen funky Kost\u00fcme (von heute Morgen?) und spitze Partyh\u00fcte. Irgendwie cool, denke ich mir; die wissen, wie man Spa\u00df hat. Und trotz des Regens macht keiner Anstalten, zu gehen.<\/p>\n<p>Bis circa zehn Uhr brennen offiziell die Feuer, doch einige der Leute beginnen bereits fr\u00fcher, sich zu entfernen, was sicher dem Regen geschuldet ist, denn Regenschirme haben nur die wenigsten dabei. Die Menschen gehen nun nach Hause, um sich einer weiteren, typisch isl\u00e4ndischen Tradition zu widmen: der j\u00e4hrlich zum Jahresabschluss ausgestrahlten Sketch-Comedyshow.<\/p>\n<p>&nbsp;<\/p>\n<h3>\u00c1ram\u00f3taskaup, die j\u00e4hrliche Sketch- Comedyshow<\/h3>\n<p>Sie geh\u00f6rt in Island zum Jahresabschluss wie bei uns das obligatorische Glas Sekt. In der Sketch-Comedyshow, die seit 1966 jedes Jahr am Abend um 22:30 Uhr ausgestrahlt wird, werden die H\u00f6hepunkte und Schlagzeilen des Jahres auf die Schippe genommen und sie ist auch ein beliebtes Unterhaltungsthema auf den Partys, die die feierw\u00fctigen Isl\u00e4nder im Anschluss an das Feuerwerk besuchen. Leider ist es keine Tradition, an der man als Tourist einfach so teilnehmen kann, es sei denn, man versteht die Sprache. Trotzdem interessant zu wissen, dass es das gibt\u2026 ?<\/p>\n<p>&nbsp;<\/p>\n<h3>Das Feuerwerk in Reykjavik<\/h3>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25402\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20200101_000330\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20200101_000330\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25402\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000330.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Das Feuerwerk in Reykjavik hat es in sich. Bereits einige Tage vor Silvester beginnen schon die ersten, ihre Raketen abzufeuern und die Nacht zum Neuen Jahr ist lediglich der fulminante H\u00f6hepunkt. Isl\u00e4nder sind leidenschaftliche Fans der Feuerwerksk\u00f6rper, im Schnitt geben sie jedes Jahr rund umgerechnet hundert Euro f\u00fcr das farbig leuchtende Spektakel aus. Eigentlich sind die Feuerwerke zum Jahresende eine recht junge Tradition, erst seit 1970 wurden die ersten Feuerwerksk\u00f6rper in Reykjavik verkauft.<\/p>\n<p>Inzwischen hat der freiwillige Rettungsdienst ICE-SAR den Verkauf \u00fcbernommen und finanzieren sich zum Teil \u00fcber die Einnahmen. Und da sie den Rettungsdienst nat\u00fcrlich unterst\u00fctzen wollen, kaufen die Menschen schon mal die L\u00e4den leer und feuern in den Himmel, was das Zeug h\u00e4lt. 2015 sollen sie mehr als f\u00fcnfhundert Tonnen an Feuerwerksk\u00f6rpern abgefeuert haben.<\/p>\n<p>Und das k\u00f6nnen sie gut \u2013 wenn man hier in Island was drauf hat, dann ist es Pyrotechnik. Das Spektakel ist einmalig, vor allem wenn man bedenkt, dass alle Raketen, die den n\u00e4chtlichen Himmel erleuchten, ausschlie\u00dflich von privat abgeschossen werden. Und die ungeduldigsten von ihnen knallen schon den ganzen Abend. Und gerade in diesem Jahr kann ich die Begeisterung und die Ungeduld besonders gut verstehen, denn ab dem Jahr 2020 soll ein Verbot der Silvesterfeuerwerke beschlossen worden sein.<\/p>\n<p>Im Hostel habe ich es geschafft, nach dem regnerischen Besuch der Lagerfeuer einigerma\u00dfen meine Kleidung zu trocknen \u2013 nach den Aramotabrenna-Feuern rieche ich wie ein gegrilltes W\u00fcrstchen.<\/p>\n<p>Diesmal bin ich schlauer und nehme, ehe ich mein Domizil auf Zeit verlasse, den schicken, gelben Regenmantel mit. Mit den klobrigen, aber regenfesten Schneeschuhen und dem dicken Schal \u00fcber Mund und Nase sehe ich zwar nicht sehr sexy und nach Party aus, aber mir ist warm und ich bleibe trocken. Das hiesige Wetter ist ein guter Lehrmeister.<\/p>\n<figure id=\"attachment_25073\" aria-describedby=\"caption-attachment-25073\" style=\"width: 442px\" class=\"wp-caption alignleft\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25073\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2020\/03\/16\/ab-nach-draussen-auch-bei-schmuddelwetter\/20191231_233909\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_233909\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Letztes Jahr in Reykjavik: weder sch\u00f6n noch sexy, aber warm\u2026&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?fit=1020%2C496&amp;ssl=1\" class=\" wp-image-25073\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?resize=442%2C215&#038;ssl=1\" alt=\"\" width=\"442\" height=\"215\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/03\/20191231_233909.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 442px) 100vw, 442px\" \/><figcaption id=\"caption-attachment-25073\" class=\"wp-caption-text\">Letztes Jahr in Reykjavik: weder sch\u00f6n noch sexy, aber warm\u2026<\/figcaption><\/figure>\n<p>F\u00fcr mich stehen zwei Locations zur Auswahl, um mir das sensationelle Spektakel anzusehen. Zum einen der Vorplatz der Hallgr\u00edmskirkja Kathedrale, wo die halbe Stadt hin str\u00f6mt, um ihre Raketen abzufeuern. Die Kathedrale war ein Tipp eines Isl\u00e4nders, den ich zwei Tage vorher am alten Hafen von Reykjavik getroffen hatte. Dort sehe ich die Feuerwerke aus n\u00e4chster N\u00e4he und bin mittendrin im Geschehen.<\/p>\n<p>Die zweite Option ist ein sch\u00f6ner Platz am See, den ich mir w\u00e4hrend meiner Suche nach dem Lagerfeuer ausgeguckt habe. Hier werde ich \u2013 so vermute ich \u2013 etwas abseits des Spektakels sein, daf\u00fcr habe ich einen grandiosen Blick auf die Skyline der Stadt mit ihrer Hallgr\u00edmskirkja Kirche, die sich im stillen, dunklen Wasser des nachtschwarzen Sees spiegelt. Ein wundersch\u00f6ner Ort. Wie man dem Titelbild entnehmen kann, habe ich mich f\u00fcr Option Nummer zwei entschieden.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25403\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20200101_000549\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?fit=996%2C2048&amp;ssl=1\" data-orig-size=\"996,2048\" data-comments-opened=\"1\" data-image-title=\"20200101_000549\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?fit=498%2C1024&amp;ssl=1\" class=\"alignnone size-full wp-image-25403\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?resize=996%2C2048&#038;ssl=1\" alt=\"\" width=\"996\" height=\"2048\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?w=996&amp;ssl=1 996w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?resize=146%2C300&amp;ssl=1 146w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?resize=498%2C1024&amp;ssl=1 498w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?resize=768%2C1579&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?resize=747%2C1536&amp;ssl=1 747w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000549.jpg?resize=29%2C60&amp;ssl=1 29w\" sizes=\"auto, (max-width: 996px) 100vw, 996px\" \/><\/p>\n<p>Vom Hostel bis zum See Tj\u00f6rnin ist es nicht weit. Doch die rund zwei Kilometer werden durch immer neue Detonationen unterbrochen, bei denen ich sofort wieder den Kopf hebe und die wundersch\u00f6nen Feuerwerke am Himmel betrachte, die meist gleich neben mir am Himmel erscheinen. Nach dem Motto \u201ealles muss weg\u201c kommt noch vor der Zeit alles an Raketen zum Einsatz, was die Stadtbewohner so aufzubieten haben.<\/p>\n<p>Alle meinen Neujahresgl\u00fcckw\u00fcnsche an Freunde und Familie habe ich bereits vor einer Stunde abgesendet, da Island, bedingt durch die Zeitverschiebung, erst eine Stunde sp\u00e4ter ins Neue Jahr kommt. Doch meine Mutter ist noch wach und da ich nicht ganz alleine sein will, schicken wir<br \/>\nuns Sprachnachrichten hin und her.<\/p>\n<p>Der Tj\u00f6rniner See stellt sich als eine gute Wahl heraus. Es haben sich mehr Menschen hier versammelt als zuerst gedacht, doch bei weitem nicht so viele, dass man sich auf die F\u00fc\u00dfe treten m\u00fcsste. Die Feuerwerke werden in einem angenehmen Abstand abgefeuert und trotzdem bin ich mitten drin, ohne Angst zu haben, dass mir ein B\u00f6ller auf die F\u00fc\u00dfe f\u00e4llt. Doch das passiert hier eher nicht, denn die begeisterten Isl\u00e4nder sind Profis, dank jahrelanger \u00dcbung. Viele tragen auch jetzt noch, in dieser Silvesternacht, Partyh\u00fcte und lustige oder glanzvolle Kost\u00fcme, mit denen nach Mitternacht der n\u00e4chste Club gest\u00fcrmt wird. Ja, einige sind verkleidet und irgendwie geh\u00f6rt es scheinbar zur Neujahresfeier dazu.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25404\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20200101_000231\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20200101_000231\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25404\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000231.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Um zw\u00f6lf Ortszeit leuchtet die gesamte Stadt auf. Die Enten im Schilf beginnen, laut und aufgeregt zu schnattern. Wo man hinschaut, brennt der Himmel, ob genau neben \u2013 oder \u00fcber mir oder rundum \u00fcber der bunt beleuchteten Skyline, die sich bis dato still und malerisch im See spiegelte. Vorbei ist es nun mit Stille und Beschaulichkeit, jetzt wird gefeiert. Schwarzgraue Rauchschwaden ziehen durch die Nacht, es riecht nach Pulver und Rauch. Die Luft wird tr\u00fcb und die Rauchwolken, die immer wieder aufleuchten in rot, wei\u00df und gr\u00fcn, sehen wie eine fantastische Welt aus.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25405\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_235116\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_235116\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25405\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235116.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25406\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_235117\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_235117\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25406\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235117.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25407\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_235358\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_235358\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25407\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235358.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25408\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20191231_235944\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20191231_235944\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25408\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20191231_235944.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25409\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20200101_000303\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20200101_000303\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25409\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000303.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"25410\" data-permalink=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/20200101_002022\/\" data-orig-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?fit=2048%2C996&amp;ssl=1\" data-orig-size=\"2048,996\" data-comments-opened=\"1\" data-image-title=\"20200101_002022\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Januar 2020, Silvester in Reykjavik&lt;\/p&gt;\n\" data-large-file=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?fit=1020%2C496&amp;ssl=1\" class=\"alignnone size-full wp-image-25410\" src=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?resize=1020%2C496&#038;ssl=1\" alt=\"\" width=\"1020\" height=\"496\" srcset=\"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?w=2048&amp;ssl=1 2048w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?resize=300%2C146&amp;ssl=1 300w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?resize=1024%2C498&amp;ssl=1 1024w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?resize=768%2C374&amp;ssl=1 768w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?resize=1536%2C747&amp;ssl=1 1536w, https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_002022.jpg?resize=123%2C60&amp;ssl=1 123w\" sizes=\"auto, (max-width: 1020px) 100vw, 1020px\" \/><\/p>\n<p>Etwa f\u00fcnfzehn Minuten lang brennt rund um mich der Himmel. Mein Freund ist wach geblieben und schickt mir Gl\u00fcckw\u00fcnsche von der Nordsee. Dann wird es langsam wieder ruhig um mich herum und ich muss zugeben, ich bin leicht entt\u00e4uscht. Nur noch vereinzelt fliegen die Raketen und ich muss daran denken, wie schade es doch ist, so viel an Munition noch vor der Zeit verschossen zu haben.<\/p>\n<p>Langsam zerstreuen sich auch die Menschen um mich rum, ziehen weiter, werden vermutlich nun durch die Bars und Kneipen ziehen, die am Silvester die ganze Nacht \u00fcber ge\u00f6ffnet haben. Ich sehe einige, die ihren M\u00fcll und die \u00dcberreste der verbrannten Feuerwerksk\u00f6rper wieder aufsammeln. Ich laufe zur\u00fcck durch die Nacht. Mitten auf einer Stra\u00dfenkreuzung werden von Jugendlichen B\u00f6llerreste verbrannt; es lodert ein kleines Feuerchen vor sich hin.<\/p>\n<p>Warum nicht, heute hat ja schon genug gebrannt.<\/p>\n<p>Ich gehe nicht feiern. Als ich im Hostel ankomme, bereite ich mich auf die R\u00fcckreise vor. Heute Morgen um vier wird mich der Flughafentransfer abholen\u2026<\/p>\n<div class=\"shariff shariff-align-left shariff-widget-align-left\" data-services=\"facebook%7Cpinterest%7Ctumblr\" data-url=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/\" data-timestamp=\"1758487714\" data-backendurl=\"https:\/\/stefan-taege.de\/kasia\/wp-json\/shariff\/v1\/share_counts?\"><ul class=\"shariff-buttons theme-round orientation-horizontal buttonsize-medium\"><li class=\"shariff-button twitter shariff-nocustomcolor\" style=\"background-color:#595959\"><a href=\"https:\/\/twitter.com\/share?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2025%2F10%2F05%2Fso-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik%2F&text=So%20kommt%20Island%20ins%20Neue%20Jahr%20%E2%80%93%20Mein%20Silvester%20in%20Reykjavik\" title=\"Bei X teilen\" aria-label=\"Bei X teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#000; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 24 24\"><path fill=\"#000\" d=\"M14.258 10.152L23.176 0h-2.113l-7.747 8.813L7.133 0H0l9.352 13.328L0 23.973h2.113l8.176-9.309 6.531 9.309h7.133zm-2.895 3.293l-.949-1.328L2.875 1.56h3.246l6.086 8.523.945 1.328 7.91 11.078h-3.246zm0 0\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button facebook shariff-nocustomcolor\" style=\"background-color:#4273c8\"><a href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2025%2F10%2F05%2Fso-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik%2F\" title=\"Bei Facebook teilen\" aria-label=\"Bei Facebook teilen\" role=\"button\" rel=\"nofollow\" class=\"shariff-link\" style=\"; background-color:#3b5998; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 18 32\"><path fill=\"#3b5998\" d=\"M17.1 0.2v4.7h-2.8q-1.5 0-2.1 0.6t-0.5 1.9v3.4h5.2l-0.7 5.3h-4.5v13.6h-5.5v-13.6h-4.5v-5.3h4.5v-3.9q0-3.3 1.9-5.2t5-1.8q2.6 0 4.1 0.2z\"\/><\/svg><\/span><span data-service=\"facebook\" style=\"color:#3b5998\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button pinterest shariff-nocustomcolor\" style=\"background-color:#e70f18\"><a href=\"https:\/\/www.pinterest.com\/pin\/create\/link\/?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2025%2F10%2F05%2Fso-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik%2F&media=https%3A%2F%2Fstefan-taege.de%2Fkasia%2Fwp-content%2Fuploads%2F2020%2F04%2F20200101_000238-e1587242816805.jpg&description=So%20kommt%20Island%20ins%20Neue%20Jahr%20%E2%80%93%20Mein%20Silvester%20in%20Reykjavik\" title=\"Bei Pinterest pinnen\" aria-label=\"Bei Pinterest pinnen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#cb2027; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#cb2027\" d=\"M27.4 16q0 3.7-1.8 6.9t-5 5-6.9 1.9q-2 0-3.9-0.6 1.1-1.7 1.4-2.9 0.2-0.6 1-3.8 0.4 0.7 1.3 1.2t2 0.5q2.1 0 3.8-1.2t2.7-3.4 0.9-4.8q0-2-1.1-3.8t-3.1-2.9-4.5-1.2q-1.9 0-3.5 0.5t-2.8 1.4-2 2-1.2 2.3-0.4 2.4q0 1.9 0.7 3.3t2.1 2q0.5 0.2 0.7-0.4 0-0.1 0.1-0.5t0.2-0.5q0.1-0.4-0.2-0.8-0.9-1.1-0.9-2.7 0-2.7 1.9-4.6t4.9-2q2.7 0 4.2 1.5t1.5 3.8q0 3-1.2 5.2t-3.1 2.1q-1.1 0-1.7-0.8t-0.4-1.9q0.1-0.6 0.5-1.7t0.5-1.8 0.2-1.4q0-0.9-0.5-1.5t-1.4-0.6q-1.1 0-1.9 1t-0.8 2.6q0 1.3 0.4 2.2l-1.8 7.5q-0.3 1.2-0.2 3.2-3.7-1.6-6-5t-2.3-7.6q0-3.7 1.9-6.9t5-5 6.9-1.9 6.9 1.9 5 5 1.8 6.9z\"\/><\/svg><\/span><span data-service=\"pinterest\" style=\"color:#cb2027\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button tumblr shariff-nocustomcolor\" style=\"background-color:#529ecc\"><a href=\"https:\/\/www.tumblr.com\/widgets\/share\/tool?posttype=link&canonicalUrl=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2025%2F10%2F05%2Fso-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik%2F&tags=stefan-taege.de\" title=\"Bei tumblr teilen\" aria-label=\"Bei tumblr teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#36465d; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#36465d\" d=\"M18 14l0 7.3c0 1.9 0 2.9 0.2 3.5 0.2 0.5 0.7 1.1 1.2 1.4 0.7 0.4 1.5 0.6 2.4 0.6 1.6 0 2.6-0.2 4.2-1.3v4.8c-1.4 0.6-2.6 1-3.7 1.3-1.1 0.3-2.3 0.4-3.6 0.4-1.5 0-2.3-0.2-3.4-0.6-1.1-0.4-2.1-0.9-2.9-1.6-0.8-0.7-1.3-1.4-1.7-2.2s-0.5-1.9-0.5-3.4v-11.2h-4.3v-4.5c1.3-0.4 2.7-1 3.6-1.8 0.9-0.8 1.6-1.7 2.2-2.7 0.5-1.1 0.9-2.4 1.1-4.1h5.2l0 8h8v6h-8z\"\/><\/svg><\/span><span data-service=\"tumblr\" style=\"color:#36465d\" class=\"shariff-count shariff-hidezero\"><\/span>&nbsp;<\/a><\/li><li class=\"shariff-button xing shariff-nocustomcolor\" style=\"background-color:#29888a\"><a href=\"https:\/\/www.xing.com\/spi\/shares\/new?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2025%2F10%2F05%2Fso-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik%2F\" title=\"Bei XING teilen\" aria-label=\"Bei XING teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#126567; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 25 32\"><path fill=\"#126567\" d=\"M10.7 11.9q-0.2 0.3-4.6 8.2-0.5 0.8-1.2 0.8h-4.3q-0.4 0-0.5-0.3t0-0.6l4.5-8q0 0 0 0l-2.9-5q-0.2-0.4 0-0.7 0.2-0.3 0.5-0.3h4.3q0.7 0 1.2 0.8zM25.1 0.4q0.2 0.3 0 0.7l-9.4 16.7 6 11q0.2 0.4 0 0.6-0.2 0.3-0.6 0.3h-4.3q-0.7 0-1.2-0.8l-6-11.1q0.3-0.6 9.5-16.8 0.4-0.8 1.2-0.8h4.3q0.4 0 0.5 0.3z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button rss shariff-nocustomcolor\" style=\"background-color:#ff8c00\"><a href=\"https:\/\/stefan-taege.de\/kasia\/feed\/rss\/\" title=\"RSS-feed\" aria-label=\"RSS-feed\" role=\"button\" class=\"shariff-link\" style=\"; background-color:#fe9312; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 32 32\"><path fill=\"#fe9312\" d=\"M4.3 23.5c-2.3 0-4.3 1.9-4.3 4.3 0 2.3 1.9 4.2 4.3 4.2 2.4 0 4.3-1.9 4.3-4.2 0-2.3-1.9-4.3-4.3-4.3zM0 10.9v6.1c4 0 7.7 1.6 10.6 4.4 2.8 2.8 4.4 6.6 4.4 10.6h6.2c0-11.7-9.5-21.1-21.1-21.1zM0 0v6.1c14.2 0 25.8 11.6 25.8 25.9h6.2c0-17.6-14.4-32-32-32z\"\/><\/svg><\/span><\/a><\/li><li class=\"shariff-button linkedin shariff-nocustomcolor\" style=\"background-color:#1488bf\"><a href=\"https:\/\/www.linkedin.com\/sharing\/share-offsite\/?url=https%3A%2F%2Fstefan-taege.de%2Fkasia%2F2025%2F10%2F05%2Fso-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik%2F\" title=\"Bei LinkedIn teilen\" aria-label=\"Bei LinkedIn teilen\" role=\"button\" rel=\"noopener nofollow\" class=\"shariff-link\" style=\"; background-color:#0077b5; color:#fff\" target=\"_blank\"><span class=\"shariff-icon\" style=\"\"><svg width=\"32px\" height=\"20px\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 27 32\"><path fill=\"#0077b5\" d=\"M6.2 11.2v17.7h-5.9v-17.7h5.9zM6.6 5.7q0 1.3-0.9 2.2t-2.4 0.9h0q-1.5 0-2.4-0.9t-0.9-2.2 0.9-2.2 2.4-0.9 2.4 0.9 0.9 2.2zM27.4 18.7v10.1h-5.9v-9.5q0-1.9-0.7-2.9t-2.3-1.1q-1.1 0-1.9 0.6t-1.2 1.5q-0.2 0.5-0.2 1.4v9.9h-5.9q0-7.1 0-11.6t0-5.3l0-0.9h5.9v2.6h0q0.4-0.6 0.7-1t1-0.9 1.6-0.8 2-0.3q3 0 4.9 2t1.9 6z\"\/><\/svg><\/span><\/a><\/li><\/ul><\/div>","protected":false},"excerpt":{"rendered":"<p>Dieser Artikel erschien bereits am 04.01.2020 Silvester in Reykjavik: schon am Morgen startet der Silvesterlauf in Verkleidung, abends gibt es &hellip; <\/p>\n","protected":false},"author":1,"featured_media":25382,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1292,2495],"tags":[2522,2523,2494,79,2524,2525,2526],"class_list":["post-23996","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-island","tag-aramotabrenna","tag-new-years-eve-run","tag-reykjavik","tag-silvester","tag-silvesterfeuerwerk","tag-silvesterlagerfeuer","tag-silvesterlauf"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik - windrose.rocks<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Kasia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"27\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/\"},\"author\":{\"name\":\"Kasia\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\"},\"headline\":\"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik\",\"datePublished\":\"2025-10-05T06:17:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/\"},\"wordCount\":4127,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1\",\"keywords\":[\"\u00c1ram\u00f3tabrenna\",\"New Years Eve Run\",\"Reykjavik\",\"silvester\",\"Silvesterfeuerwerk\",\"Silvesterlagerfeuer\",\"Silvesterlauf\"],\"articleSection\":[\"Europa\",\"Island\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/\",\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/\",\"name\":\"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik - windrose.rocks\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1\",\"datePublished\":\"2025-10-05T06:17:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#primaryimage\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/stefan-taege.de\\\/kasia\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1\",\"width\":2046,\"height\":995},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/2025\\\/10\\\/05\\\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#website\",\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\",\"name\":\"windrose.rocks\",\"description\":\"Erz\u00e4hlungen einer Reisenden\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/#\\\/schema\\\/person\\\/873b01562fbd03e9caa51512b2cb800f\",\"name\":\"Kasia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg\",\"caption\":\"Kasia\"},\"description\":\"Hi, ich bin Kasia, die Stimme von \\\"windrose.rocks\\\" :-) Treibt Dich die Frage um, was sich denn alles jenseits der heimischen Couch verbirgt, bist Du rastlos und neugierig wie ich und sp\u00fcrst den Drang in Dir, in die Welt hinaus zu gehen? Dann tue es! Ich nehme Dich mit auf meine Reisen und lasse Dich hautnah das Unterwegs sein miterleben - in all seinen Facetten. Lass Dich inspirieren, komm mit mir und warte nicht l\u00e4nger, denn... die Welt ist so gro\u00df und wir sind so klein, und es gibt noch so viel zu sehen! Die Welt wartet auf uns.\",\"sameAs\":[\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/\"],\"url\":\"https:\\\/\\\/stefan-taege.de\\\/kasia\\\/author\\\/kasia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik - windrose.rocks","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/","twitter_misc":{"Verfasst von":"Kasia","Gesch\u00e4tzte Lesezeit":"27\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#article","isPartOf":{"@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/"},"author":{"name":"Kasia","@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f"},"headline":"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik","datePublished":"2025-10-05T06:17:27+00:00","mainEntityOfPage":{"@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/"},"wordCount":4127,"commentCount":0,"image":{"@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1","keywords":["\u00c1ram\u00f3tabrenna","New Years Eve Run","Reykjavik","silvester","Silvesterfeuerwerk","Silvesterlagerfeuer","Silvesterlauf"],"articleSection":["Europa","Island"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/","url":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/","name":"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik - windrose.rocks","isPartOf":{"@id":"https:\/\/stefan-taege.de\/kasia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#primaryimage"},"image":{"@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#primaryimage"},"thumbnailUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1","datePublished":"2025-10-05T06:17:27+00:00","author":{"@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f"},"breadcrumb":{"@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#primaryimage","url":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1","contentUrl":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1","width":2046,"height":995},{"@type":"BreadcrumbList","@id":"https:\/\/stefan-taege.de\/kasia\/2025\/10\/05\/so-kommt-island-ins-neue-jahr-mein-silvester-in-reykjavik\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/stefan-taege.de\/kasia\/"},{"@type":"ListItem","position":2,"name":"So kommt Island ins Neue Jahr \u2013 Mein Silvester in Reykjavik"}]},{"@type":"WebSite","@id":"https:\/\/stefan-taege.de\/kasia\/#website","url":"https:\/\/stefan-taege.de\/kasia\/","name":"windrose.rocks","description":"Erz\u00e4hlungen einer Reisenden","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stefan-taege.de\/kasia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/stefan-taege.de\/kasia\/#\/schema\/person\/873b01562fbd03e9caa51512b2cb800f","name":"Kasia","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","url":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1c67397e33cd4beae4560d74391fdad75dfa2a9640ebc70b63890dbd4232d509?s=96&d=mm&r=pg","caption":"Kasia"},"description":"Hi, ich bin Kasia, die Stimme von \"windrose.rocks\" :-) Treibt Dich die Frage um, was sich denn alles jenseits der heimischen Couch verbirgt, bist Du rastlos und neugierig wie ich und sp\u00fcrst den Drang in Dir, in die Welt hinaus zu gehen? Dann tue es! Ich nehme Dich mit auf meine Reisen und lasse Dich hautnah das Unterwegs sein miterleben - in all seinen Facetten. Lass Dich inspirieren, komm mit mir und warte nicht l\u00e4nger, denn... die Welt ist so gro\u00df und wir sind so klein, und es gibt noch so viel zu sehen! Die Welt wartet auf uns.","sameAs":["https:\/\/stefan-taege.de\/kasia\/"],"url":"https:\/\/stefan-taege.de\/kasia\/author\/kasia\/"}]}},"jetpack_shortlink":"https:\/\/wp.me\/p7Ku1E-6f2","jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/i0.wp.com\/stefan-taege.de\/kasia\/wp-content\/uploads\/2020\/04\/20200101_000238-e1587242816805.jpg?fit=2046%2C995&ssl=1","_links":{"self":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/23996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/comments?post=23996"}],"version-history":[{"count":8,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/23996\/revisions"}],"predecessor-version":[{"id":48027,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/posts\/23996\/revisions\/48027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/media\/25382"}],"wp:attachment":[{"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/media?parent=23996"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/categories?post=23996"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stefan-taege.de\/kasia\/wp-json\/wp\/v2\/tags?post=23996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}